{"id":1240,"date":"2009-02-02T07:48:19","date_gmt":"2009-02-02T09:48:19","guid":{"rendered":"https:\/\/comoaprenderjapones.net\/?p=1240"},"modified":"2018-02-25T16:53:33","modified_gmt":"2018-02-25T19:53:33","slug":"familia-do-w-e-a-consoante-n-em-hiragana","status":"publish","type":"post","link":"https:\/\/comoaprenderjapones.net\/ar\/familia-do-w-e-a-consoante-n-em-hiragana\/","title":{"rendered":"A fam\u00edlia do W e a consoante N em hiragana"},"content":{"rendered":"<div class=\"c95246580650d4be5df24a0ae1408903\" data-index=\"2\" style=\"float: none; margin:0px;\">\n<script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-0652292147574552\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<!-- Ads responsivo Inicio Post CAJap -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-0652292147574552\"\r\n     data-ad-slot=\"3298668993\"\r\n     data-ad-format=\"auto\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p><em>\u062a\u0639\u0631\u0651\u0641 \u0639\u0644\u0649 <strong>fam\u00edlia do W e a consoante N em hiragana<\/strong> \u0648\u062a\u0639\u0644\u0645 \u0643\u064a\u0641\u064a\u0629 \u0643\u062a\u0627\u0628\u0629 \u0636\u0631\u0628\u0627\u062a\u0643 \u0628\u0634\u0643\u0644 \u0635\u062d\u064a\u062d!<\/em><\/p>\n<h2>A fam\u00edlia do W e a consoante N em hiragana<\/h2>\n<p>O hiragana WA ( \u308f ) \u00e9 muito f\u00e1cil de ser confundido com o hiragana NE ( \u306d ) e com RE ( \u308c ). Percebam que eles possuem a mesma escrita, mas NE possui uma pequena volta na parte de baixo. Para diferenciar um s\u00edmbolo do outro, tive que imaginar um caminho diferente na hora de associar o caractere WA da forma usada em NE.<span id=\"more-63\"><\/span><\/p>\n<p>Percebam que o primeiro tra\u00e7o seria ( como sempre ) um ninja e o segundo tra\u00e7o \u00e9 composto por dois s\u00edmbolos: um 7 e um nariz. Assim podemos montar uma pequena historinha\u2026<\/p>\n<p>O ninja revoltado com meu amigo WAlter, bateu nele sete vezes com o numeral &#8220;7&#8221; bem no nariz at\u00e9 e o nariz de WAlter sangrar. Para lembrar do som deste s\u00edmbolo, ao falar WA de WAlter eu falo UAlter. Distorcendo as s\u00edlabas para ficar semelhante \u00e0 fala japonesa.<\/p>\n<p>Abaixo segue a ordem dos tra\u00e7os:<\/p>\n<p class=\"align-center\"><img decoding=\"async\" class=\"aligncenter wp-image-1241 size-full\" title=\"Ordem dos tra\u00e7os do hiragana WA\" src=\"https:\/\/comoaprenderjapones.net\/wp-content\/uploads\/2018\/02\/hiragana-wa-ordem-dos-tracos.jpg\" alt=\"Ordem dos tra\u00e7os do hiragana WA - fam\u00edlia do W e a consoante N em hiragana\" width=\"202\" height=\"99\" srcset=\"https:\/\/comoaprenderjapones.net\/wp-content\/uploads\/2018\/02\/hiragana-wa-ordem-dos-tracos.jpg 202w, https:\/\/comoaprenderjapones.net\/wp-content\/uploads\/2018\/02\/hiragana-wa-ordem-dos-tracos-960x472.jpg 960w\" sizes=\"(max-width: 202px) 100vw, 202px\" \/><\/p>\n<p>WO = \u3092<\/p>\n<p>Se observar cuidadosamente, o pen\u00faltimo s\u00edmbolo do hiragana parece ser composto por tr\u00eas letras do nosso alfabeto: T, L ( entortado para baixo ) e C.<\/p>\n<p>Para lembrar das letras que formam este hiragana eu associei o mesmo com a historinha de um Tatu gigante Lambendo seu pr\u00f3prio Casco. Junto a isso, basta lembrar que o nome da tartaruga \u00e9 U\u00f3li ( Wally ).<\/p>\n<p class=\"align-center\"><img decoding=\"async\" class=\"aligncenter wp-image-1243 size-full\" title=\"Ordem dos tra\u00e7os do hiragana WO\" src=\"https:\/\/comoaprenderjapones.net\/wp-content\/uploads\/2018\/02\/hiragana-wo-ordem-dos-tracos.jpg\" alt=\"Ordem dos tra\u00e7os do hiragana WO\" width=\"296\" height=\"95\" \/><\/p>\n<p><br \/>\nN = \u3093<\/p>\n<p>Este \u00e9 o hiragana mais f\u00e1cil de aprender, ele \u00e9 id\u00eantico ao nosso &#8220;h&#8221; em it\u00e1lico ( deitado ) e com tra\u00e7os mais ondulados. Da\u00ed \u00e9 s\u00f3 imaginar uma pessoa com problemas de dic\u00e7\u00e3o. Assim como algumas pessoas trocam o R pelo L, essa pessoa troca o H pelo N.<\/p>\n<p>O legal da letra \u3093 \u00e9 que ela possui o mesmo uso do N na l\u00edngua portuguesa, podendo se juntar com vogais ou outras s\u00edlabas para formar sons nasais como: na, ana, no, ontem, ni, inverno\u2026<\/p>\n<p class=\"align-center\"><img decoding=\"async\" class=\"aligncenter wp-image-1244 size-full\" title=\"Ordem dos tra\u00e7os do hiragana N\" src=\"https:\/\/comoaprenderjapones.net\/wp-content\/uploads\/2018\/02\/hiragana-n-ordem-dos-tracos.jpg\" alt=\"Ordem dos tra\u00e7os do hiragana N\" width=\"99\" height=\"77\" \/><\/p>\n<h2>\u062a\u0645\u0631\u064a\u0646 \u0627\u0644\u062e\u0637 \u0627\u0644\u064a\u0627\u0628\u0627\u0646\u064a<\/h2>\n<p>\u0627\u062e\u062a\u0631\u00a0<a href=\"https:\/\/comoaprenderjapones.net\/ar\/hiragana-tabela-completa\/\">\u0631\u0645\u0648\u0632 \u0627\u0644\u0623\u0628\u062c\u062f\u064a\u0629 \u0627\u0644\u064a\u0627\u0628\u0627\u0646\u064a\u0629<\/a>\u00a0\u0648\u0627\u0646\u0642\u0631 \u0639\u0644\u0649 \u0632\u0631 \u0625\u0646\u0634\u0627\u0621 \u0641\u064a\u00a0<a href=\"https:\/\/comoaprenderjapones.net\/ar\/in\/imprimir-para-treinar-kanas-e-kanjis\/\" target=\"_blank\" rel=\"noopener\">\u0648\u0631\u0642\u0629 \u062a\u062f\u0631\u064a\u0628 \u0639\u0644\u0649 \u0627\u0644\u0643\u0627\u0646\u0627 \u0648\u0627\u0644\u0643\u0627\u0646\u062c\u064a<\/a>\u00a0. \u0633\u062a\u0641\u062a\u062d \u0628\u0639\u062f \u0630\u0644\u0643 \u0646\u0627\u0641\u0630\u0629 \u062c\u062f\u064a\u062f\u0629 \u0628\u0627\u0644\u0645\u0644\u0641 \u0627\u0644\u0642\u0627\u0628\u0644 \u0644\u0644\u0637\u0628\u0627\u0639\u0629. \u062b\u0645 \u0643\u0644 \u0645\u0627 \u0639\u0644\u064a\u0643 \u0641\u0639\u0644\u0647 \u0628\u0639\u062f \u0630\u0644\u0643 \u0647\u0648 \u0637\u0628\u0627\u0639\u062a\u0647 \u0648\u062a\u063a\u0637\u064a\u0629 \u0631\u0645\u0648\u0632 \u0627\u0644\u0647\u064a\u0631\u0627\u063a\u0627\u0646\u0627 \u0627\u0644\u0631\u0645\u0627\u062f\u064a\u0629 \u062b\u0645 \u062d\u0627\u0648\u0644 \u0643\u062a\u0627\u0628\u062a\u0647 \u0628\u0646\u0641\u0633\u0643. \u0641\u0642\u0637 \u0627\u0637\u0628\u0639 \u0648\u062a\u062f\u0631\u0628!<\/p>\n<table style=\"height: 45px\" border=\"0\" width=\"279\" cellspacing=\"2\" cellpadding=\"2\">\n<tbody>\n<tr>\n<td align=\"left\" valign=\"middle\">\u308f<\/td>\n<td align=\"left\" valign=\"middle\">\u3092<\/td>\n<td align=\"left\" valign=\"middle\">\u3093<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Conhe\u00e7a a fam\u00edlia do W e a consoante N em hiragana e saiba como escrever corretamente seus tra\u00e7os! A fam\u00edlia do W e a consoante N em hiragana O hiragana WA ( \u308f ) \u00e9<\/p>","protected":false},"author":18,"featured_media":1242,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46,47],"tags":[16,54],"class_list":["post-1240","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alfabeto-japones","category-alfabeto-japones-hiragana","tag-alfabeto-japones","tag-hiragana","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/comoaprenderjapones.net\/ar\/wp-json\/wp\/v2\/posts\/1240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comoaprenderjapones.net\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comoaprenderjapones.net\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comoaprenderjapones.net\/ar\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/comoaprenderjapones.net\/ar\/wp-json\/wp\/v2\/comments?post=1240"}],"version-history":[{"count":0,"href":"https:\/\/comoaprenderjapones.net\/ar\/wp-json\/wp\/v2\/posts\/1240\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comoaprenderjapones.net\/ar\/wp-json\/wp\/v2\/media\/1242"}],"wp:attachment":[{"href":"https:\/\/comoaprenderjapones.net\/ar\/wp-json\/wp\/v2\/media?parent=1240"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comoaprenderjapones.net\/ar\/wp-json\/wp\/v2\/categories?post=1240"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comoaprenderjapones.net\/ar\/wp-json\/wp\/v2\/tags?post=1240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}