{"id":2403,"date":"2010-01-27T09:00:35","date_gmt":"2010-01-27T11:00:35","guid":{"rendered":"https:\/\/comoaprenderjapones.net\/?p=2403"},"modified":"2018-07-01T17:12:05","modified_gmt":"2018-07-01T20:12:05","slug":"%d1%87%d0%b0%d1%81%d1%82%d0%b8%d1%86%d0%b0%d1%82%d0%b0-%d0%b4%d0%be-%d0%b2-%d1%8f%d0%bf%d0%be%d0%bd%d1%81%d0%ba%d0%b8%d1%8f-%d0%b5%d0%b7%d0%b8%d0%ba","status":"publish","type":"post","link":"https:\/\/comoaprenderjapones.net\/bg\/a-particula-to-em-japones\/","title":{"rendered":"\u0427\u0430\u0441\u0442\u0438\u0446\u0430\u0442\u0430 TO \u0432 \u044f\u043f\u043e\u043d\u0441\u043a\u0438\u044f \u0435\u0437\u0438\u043a"},"content":{"rendered":"<div class=\"5a71adb7ae8d987b220bf717cd606f5a\" data-index=\"2\" style=\"float: none; margin:0px;\">\n<script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-0652292147574552\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<!-- Ads responsivo Inicio Post CAJap -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-0652292147574552\"\r\n     data-ad-slot=\"3298668993\"\r\n     data-ad-format=\"auto\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p><em>\u041d\u0430\u0443\u0447\u0435\u0442\u0435 \u043f\u043e\u0432\u0435\u0447\u0435 \u0437\u0430 <strong>\u0447\u0430\u0441\u0442\u0438\u0446\u0430\u0442\u0430 TO \u0432 \u044f\u043f\u043e\u043d\u0441\u043a\u0438\u044f \u0435\u0437\u0438\u043a<\/strong>!<\/em><\/p>\n<p>\u042f\u043f\u043e\u043d\u0441\u043a\u0430\u0442\u0430 \u0447\u0430\u0441\u0442\u0438\u0446\u0430\u00a0<em>\u043a\u044a\u043c\u00a0<\/em>\u0435 \u0434\u0440\u0443\u0433\u0430 \u0447\u0430\u0441\u0442\u0438\u0446\u0430, \u0434\u043e\u0431\u0440\u0435 \u043f\u043e\u0437\u043d\u0430\u0442\u0430 \u043d\u0430 \u0438\u0437\u0443\u0447\u0430\u0432\u0430\u0449\u0438\u0442\u0435 \u044f\u043f\u043e\u043d\u0441\u043a\u0438 \u0435\u0437\u0438\u043a. \u041d\u0435\u0439\u043d\u0430\u0442\u0430 \u043d\u0430\u0439-\u0447\u0435\u0441\u0442\u043e \u0441\u0440\u0435\u0449\u0430\u043d\u0430 \u0444\u0443\u043d\u043a\u0446\u0438\u044f \u0435 \u043f\u0440\u043e\u0441\u0442\u043e \u0434\u0430 \u043e\u0431\u0435\u0434\u0438\u043d\u044f\u0432\u0430 \u0441\u043f\u0438\u0441\u044a\u0446\u0438 \u043e\u0442\u00a0<a title=\"\u0421\u044a\u0449\u0435\u0441\u0442\u0432\u0438\u0442\u0435\u043b\u043d\u0438 \u0438\u043c\u0435\u043d\u0430 \u0432 \u044f\u043f\u043e\u043d\u0441\u043a\u0438\u044f \u0435\u0437\u0438\u043a\" href=\"https:\/\/comoaprenderjapones.net\/bg\/%d1%81%d1%8a%d1%89%d0%b5%d1%81%d1%82%d0%b2%d0%b8%d1%82%d0%b5%d0%bb%d0%bd%d0%b8-%d0%b8%d0%bc%d0%b5%d0%bd%d0%b0-%d0%b2-%d1%8f%d0%bf%d0%be%d0%bd%d1%81%d0%ba%d0%b8-%d0%b5%d0%b7%d0%b8%d0%ba\/\">\u042f\u043f\u043e\u043d\u0441\u043a\u0438 \u0441\u044a\u0449\u0435\u0441\u0442\u0432\u0438\u0442\u0435\u043b\u043d\u0438 \u0438\u043c\u0435\u043d\u0430<\/a>\u00a0\u0438\u043b\u0438 \u0434\u043e\u0440\u0438 \u0444\u0440\u0430\u0437\u0438.<\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"alignleft size-full wp-image-2405\" src=\"https:\/\/i0.wp.com\/comoaprenderjapones.net\/wp-content\/uploads\/2018\/07\/particula-to-em-japones.gif?resize=130%2C130&#038;ssl=1\" alt=\"\u0447\u0430\u0441\u0442\u0438\u0446\u0430 \u0434\u043e \u043d\u0430 \u044f\u043f\u043e\u043d\u0441\u043a\u0438\" width=\"130\" height=\"130\" \/><\/p>\n<p>\u0417\u0430 \u0440\u0430\u0437\u043b\u0438\u043a\u0430 \u043e\u0442 \u0434\u0440\u0443\u0433\u0438\u00a0<a title=\"\u0427\u0430\u0441\u0442\u0438\u0446\u0438 \u043d\u0430 \u044f\u043f\u043e\u043d\u0441\u043a\u0438\" href=\"https:\/\/comoaprenderjapones.net\/bg\/%d1%87%d0%b0%d1%81%d1%82%d0%b8%d1%86%d0%b8-%d0%b2-%d1%8f%d0%bf%d0%be%d0%bd%d1%81%d0%ba%d0%b8%d1%8f-%d0%b5%d0%b7%d0%b8%d0%ba-2\/\">\u042f\u043f\u043e\u043d\u0441\u043a\u0438 \u0447\u0430\u0441\u0442\u0438\u0446\u0438<\/a>\u0447\u0430\u0441\u0442\u0438\u0446\u0430\u0442\u0430\u00a0<em>\u043a\u044a\u043c<\/em>\u00a0\u0432\u0438\u043d\u0430\u0433\u0438 \u0438\u0437\u0431\u0440\u043e\u044f\u0432\u0430 \u0435\u043b\u0435\u043c\u0435\u043d\u0442\u0438\u0442\u0435 \u043f\u043e \u043e\u0431\u0435\u043a\u0442\u0438\u0432\u0435\u043d \u043d\u0430\u0447\u0438\u043d, \u043a\u0430\u0442\u043e \u043f\u043e\u0441\u043e\u0447\u0432\u0430 \u0432\u0441\u0438\u0447\u043a\u0438 \u0435\u043b\u0435\u043c\u0435\u043d\u0442\u0438, \u043a\u043e\u0438\u0442\u043e \u0441\u044a\u0449\u0435\u0441\u0442\u0432\u0443\u0432\u0430\u0442 \u0432 \u0434\u0430\u0434\u0435\u043d\u0430 \u0441\u0438\u0442\u0443\u0430\u0446\u0438\u044f.<\/p>\n<h2>\u0421\u0432\u044a\u0440\u0437\u0432\u0430\u043d\u0435 \u043d\u0430 \u0434\u0443\u043c\u0438 \u0441 \u0447\u0430\u0441\u0442\u0438\u0446\u0430\u0442\u0430 \u0437\u0430<\/h2>\n<p>\u0421\u0432\u044a\u0440\u0437\u0432\u0430\u043d\u0435 \u043d\u0430 \u0434\u0443\u043c\u0438 \u0441 \u0447\u0430\u0441\u0442\u0438\u0446\u0430\u00a0<em>\u043a\u044a\u043c<\/em>\u041f\u0440\u043e\u0441\u0442\u043e \u0434\u043e\u0431\u0430\u0432\u0435\u0442\u0435 \u0447\u0430\u0441\u0442\u0438\u0446\u0430\u0442\u0430 \u043c\u0435\u0436\u0434\u0443 \u0434\u0443\u043c\u0438\u0442\u0435, \u043a\u043e\u0438\u0442\u043e \u0441\u044a\u0441\u0442\u0430\u0432\u043b\u044f\u0432\u0430\u0442 \u0441\u043f\u0438\u0441\u044a\u043a\u0430.<\/p>\n<p><strong>\u041f\u0440\u0438\u043c\u0435\u0440\u0438:<\/strong><\/p>\n<p><acronym title=\"inu to neko ga teeburu no shita ni imasu.\">\u72ac<span style=\"color: #ff6600\">\u3068<\/span>\u732b\u304c\u30c6\u30fc\u30d6\u30eb\u306e\u4e0b\u306b\u3044\u307e\u3059\u3002<\/acronym><\/p>\n<p><em>\u0418\u043c\u0430 \u043a\u0443\u0447\u0435\u00a0<span style=\"color: #ff6600\">e<\/span>\u00a0\u043a\u043e\u0442\u043a\u0430 \u043f\u043e\u0434 \u043c\u0430\u0441\u0430\u0442\u0430.<\/em><\/p>\n<p><acronym title=\"ringo to budoo ga teeburu no ue ni arimasu.\">\u308a\u3093\u3054<span style=\"color: #ff6600\">\u3068<\/span>\u3076\u3069\u3046\u304c\u30c6\u30fc\u30d6\u30eb\u306e\u4e0a\u306b\u3042\u308a\u307e\u3059\u3002<\/acronym><\/p>\n<p><acronym title=\"akai ringo to midori to budoo ga teeburu no ue ni arimasu.\">\u8d64\u3044\u308a\u3093\u3054<span style=\"color: #ff6600\">\u3068<\/span>\u7dd1\u306e\u3076\u3069\u3046\u3082\u30c6\u30fc\u30d6\u30eb\u306e\u4e0a\u306b\u3042\u308a\u307e\u3059\u3002<\/acronym><\/p>\n<p><em>\u0418\u043c\u0430 \u044f\u0431\u044a\u043b\u043a\u0438\u00a0<span style=\"color: #ff6600\">e<\/span>\u00a0\u0433\u0440\u043e\u0437\u0434\u0435 \u043d\u0430 \u043c\u0430\u0441\u0430\u0442\u0430.<\/em><\/p>\n<p><em>\u0418\u043c\u0430 \u0447\u0435\u0440\u0432\u0435\u043d\u0438 \u044f\u0431\u044a\u043b\u043a\u0438\u00a0<span style=\"color: #ff6600\">e<\/span>\u00a0\u0437\u0435\u043b\u0435\u043d\u043e \u0433\u0440\u043e\u0437\u0434\u0435 \u043d\u0430 \u043c\u0430\u0441\u0430\u0442\u0430.<\/em><\/p>\n<p><acronym title=\"watashi wa nihongo to porutogarugo to itariago to supeingo ga hanaseru.\">\u79c1\u306f\u65e5\u672c\u8a9e\u3068\u30dd\u30eb\u30c8\u30ac\u30eb\u8a9e\u3068\u30a4\u30bf\u30ea\u30a2\u8a9e\u3068\u30b9\u30da\u30a4\u30f3\u8a9e\u304c\u8a71\u305b\u308b\u3002<\/acronym><\/p>\n<p><em>\u0413\u043e\u0432\u043e\u0440\u044f (\u043c\u043e\u0433\u0430 \u0434\u0430 \u0433\u043e\u0432\u043e\u0440\u044f) \u044f\u043f\u043e\u043d\u0441\u043a\u0438 \u0435\u0437\u0438\u043a<span style=\"color: #ff6600\">,<\/span>\u00a0\u041f\u043e\u0440\u0442\u0443\u0433\u0430\u043b\u0441\u043a\u0438<span style=\"color: #ff6600\">,<\/span>\u00a0\u0418\u0442\u0430\u043b\u0438\u0430\u043d\u0441\u043a\u0438\u00a0<span style=\"color: #ff6600\">e<\/span>\u00a0\u0418\u0441\u043f\u0430\u043d\u0441\u043a\u0438 \u0435\u0437\u0438\u043a.<\/em><\/p>\n<h2>\u0421\u0432\u044a\u0440\u0437\u0432\u0430\u043d\u0435 \u043d\u0430 \u044f\u043f\u043e\u043d\u0441\u043a\u0438 \u0438\u0437\u0440\u0435\u0447\u0435\u043d\u0438\u044f \u0441 \u0447\u0430\u0441\u0442\u0438\u0446\u0430\u0442\u0430 to<\/h2>\n<p>\u0427\u0430\u0441\u0442\u0438\u0446\u0430\u0442\u0430\u00a0<em>\u043a\u044a\u043c<\/em>\u00a0\u043c\u043e\u0436\u0435 \u0434\u0430 \u043e\u0431\u0435\u0434\u0438\u043d\u044f\u0432\u0430 \u0434\u0432\u0435 \u0438\u0437\u0440\u0435\u0447\u0435\u043d\u0438\u044f \u0432 \u0435\u0434\u043d\u043e \u043d\u0430 \u044f\u043f\u043e\u043d\u0441\u043a\u0438 \u0435\u0437\u0438\u043a. \u041e\u0431\u044a\u0440\u043d\u0435\u0442\u0435 \u0432\u043d\u0438\u043c\u0430\u043d\u0438\u0435, \u0447\u0435 \u0447\u0430\u0441\u0442\u0438\u0446\u0430\u0442\u0430\u00a0<em>\u043a\u044a\u043c<\/em>\u00a0\u043d\u0435 \u043c\u043e\u0436\u0435 \u0434\u0430 \u043e\u0431\u0435\u0434\u0438\u043d\u044f\u0432\u0430 \u0438\u0437\u0440\u0435\u0447\u0435\u043d\u0438\u044f \u043e\u0442 \u0440\u0430\u0437\u043b\u0438\u0447\u043d\u0438 \u043f\u0435\u0440\u0438\u043e\u0434\u0438 (\u0440\u0430\u0437\u0434\u0435\u043b\u0435\u043d\u0438 \u0441 \u0442\u043e\u0447\u043a\u0430) \u0438\u043b\u0438 \u0434\u0430 \u0441\u0435 \u043f\u043e\u044f\u0432\u044f\u0432\u0430 \u0432 \u043d\u0430\u0447\u0430\u043b\u043e\u0442\u043e \u043d\u0430 \u0438\u0437\u0440\u0435\u0447\u0435\u043d\u0438\u044f \u043d\u0430 \u044f\u043f\u043e\u043d\u0441\u043a\u0438 \u0435\u0437\u0438\u043a.<\/p>\n<p><strong>\u041f\u0440\u0438\u043c\u0435\u0440:<\/strong><\/p>\n<p><acronym title=\"Watashi ga katta ringo to anata ga katta budoo wa teeburu no eu ni arimasu.\"><span style=\"color: #00ff00\">\u79c1\u304c\u8cb7\u3063\u305f\u308a\u3093\u3054<\/span><span style=\"color: #ff6600\">\u3068<\/span><span style=\"color: #3366ff\">\u3042\u306a\u305f\u8cb7\u3063\u305f\u3076\u3069\u3046<\/span>\u306f\u30c6\u30fc\u30d6\u30eb\u306e\u4e0a\u306b\u3042\u308a\u307e\u3059\u3002<\/acronym><\/p>\n<p><em><span style=\"color: #00ff00\">\u042f\u0431\u044a\u043b\u043a\u0438\u0442\u0435, \u043a\u043e\u0438\u0442\u043e \u043a\u0443\u043f\u0438\u0445<\/span>\u00a0<span style=\"color: #ff6600\">e<\/span>\u00a0<span style=\"color: #3366ff\">\u0433\u0440\u043e\u0437\u0434\u0435\u0442\u043e, \u043a\u043e\u0435\u0442\u043e \u0441\u0442\u0435 \u043a\u0443\u043f\u0438\u043b\u0438<\/span>\u00a0\u0441\u0430 \u043d\u0430 \u043c\u0430\u0441\u0430\u0442\u0430.<\/em><\/p>\n<h2>\u0421\u044a\u043f\u043e\u0441\u0442\u0430\u0432\u044f\u043d\u0435 \u0438 \u0441\u0440\u0430\u0432\u043d\u044f\u0432\u0430\u043d\u0435 \u043d\u0430 \u0434\u0443\u043c\u0438 \u0441 \u0447\u0430\u0441\u0442\u0438\u0446\u0430\u0442\u0430 to<\/h2>\n<p>\u041a\u043e\u0433\u0430\u0442\u043e \u0447\u0430\u0441\u0442\u0438\u0446\u0430\u0442\u0430\u00a0<em>\u043a\u044a\u043c<\/em>\u00a0\u0441\u0435 \u043f\u043e\u044f\u0432\u044f\u0432\u0430 \u043c\u0435\u0436\u0434\u0443 \u0434\u0432\u0435 \u044f\u043f\u043e\u043d\u0441\u043a\u0438 \u0441\u044a\u0449\u0435\u0441\u0442\u0432\u0438\u0442\u0435\u043b\u043d\u0438, \u0442\u043e\u0439 \u043f\u043e\u043a\u0430\u0437\u0432\u0430 \u043a\u043e\u043d\u0442\u0440\u0430\u0441\u0442 \u0438\u043b\u0438 \u0441\u0440\u0430\u0432\u043d\u0435\u043d\u0438\u0435 \u043c\u0435\u0436\u0434\u0443 \u0442\u0435\u0437\u0438 \u0434\u0432\u0435 \u0441\u044a\u0449\u0435\u0441\u0442\u0432\u0438\u0442\u0435\u043b\u043d\u0438. \u0412 \u0442\u0430\u043a\u0438\u0432\u0430 \u0441\u043b\u0443\u0447\u0430\u0438 \u0447\u0430\u0441\u0442\u0438\u0446\u0430\u0442\u0430\u00a0<em>\u043a\u044a\u043c<\/em>\u00a0\u043c\u043e\u0436\u0435 \u0434\u0430 \u0441\u0435 \u043f\u0440\u0435\u0432\u0435\u0434\u0435 \u043a\u0430\u0442\u043e\u00a0<em>e<\/em>,\u00a0<em>\u0438\u043b\u0438<\/em>,\u00a0<em>\u043c\u0435\u0436\u0434\u0443\u00a0<\/em>\u0438\u043b\u0438 \u043f\u043e\u0434\u043e\u0431\u043d\u0438 \u0438\u0437\u0440\u0430\u0437\u0438.<\/p>\n<p><strong>\u041f\u0440\u0438\u043c\u0435\u0440\u0438:<\/strong><\/p>\n<p><acronym title=\"Sukimu miruku to futsuu no miruku to dochira o kaimashoo ka?\">\u30b9\u30ad\u30e0\u30df\u30eb\u30af<span style=\"color: #ff6600\">\u3068<\/span>\u666e\u901a\u306e\u30df\u30eb\u30af\u3068\u3069\u3061\u3089\u3092\u8cb7\u3044\u307e\u3057\u3087\u3046\u304b\uff1f<\/acronym><\/p>\n<p><acronym title=\"Sukimu miruku to futsuu no miruku to dochira o kaimashoo ka?\"><\/acronym><em>\u041a\u043e\u0435 \u0442\u0440\u044f\u0431\u0432\u0430 \u0434\u0430 \u043a\u0443\u043f\u044f, \u043e\u0431\u0435\u0437\u043c\u0430\u0441\u043b\u0435\u043d\u043e \u043c\u043b\u044f\u043a\u043e?\u00a0<span style=\"color: #ff6600\">\u0438\u043b\u0438<\/span>\u00a0\u043e\u0431\u0438\u043a\u043d\u043e\u0432\u0435\u043d\u043e \u043c\u043b\u044f\u043a\u043e?<\/em><\/p>\n<p><acronym title=\"Natsu to fuyu to de wa kionwa taihen chigaimasu.\">\u590f\u3068\u51ac<span style=\"color: #ff6600\">\u3068<\/span>\u3067\u306f\u6c17\u6e29\u306f\u5927\u5909\u9055\u3044\u307e\u3059\u3002<\/acronym><\/p>\n<p><em><span style=\"color: #ff6600\">\u041c\u0435\u0436\u0434\u0443<\/span>\u00a0\u043b\u044f\u0442\u043e\u00a0<span style=\"color: #ff6600\">e<\/span>\u00a0\u041f\u0440\u0435\u0437 \u0437\u0438\u043c\u0430\u0442\u0430 \u0438\u043c\u0430 \u0433\u043e\u043b\u044f\u043c\u0430 \u0442\u0435\u043c\u043f\u0435\u0440\u0430\u0442\u0443\u0440\u043d\u0430 \u0440\u0430\u0437\u043b\u0438\u043a\u0430.<\/em><br \/>\n<br \/>\n\u041e\u0431\u044a\u0440\u043d\u0435\u0442\u0435 \u0432\u043d\u0438\u043c\u0430\u043d\u0438\u0435, \u0447\u0435 \u0437\u0430 \u0434\u0430 \u0437\u043d\u0430\u0435\u0442\u0435 \u043f\u0440\u0430\u0432\u0438\u043b\u043d\u043e\u0442\u043e \u0437\u043d\u0430\u0447\u0435\u043d\u0438\u0435 \u043d\u0430 \u0447\u0430\u0441\u0442\u0438\u0446\u0430\u0442\u0430\u00a0<em>\u043a\u044a\u043c\u00a0<\/em>\u0442\u0440\u044f\u0431\u0432\u0430 \u0434\u0430 \u0440\u0430\u0437\u0431\u0435\u0440\u0435\u0442\u0435 \u043a\u043e\u043d\u0442\u0435\u043a\u0441\u0442\u0430 \u043d\u0430 \u0438\u0437\u0440\u0435\u0447\u0435\u043d\u0438\u0435\u0442\u043e. \u041a\u043e\u0433\u0430\u0442\u043e \u0441\u0442\u0430\u0432\u0430 \u0434\u0443\u043c\u0430 \u0437\u0430 \u0432\u044a\u043f\u0440\u043e\u0441, \u043e\u0431\u0438\u043a\u043d\u043e\u0432\u0435\u043d\u043e\u00a0<em>\u043a\u044a\u043c<\/em>\u00a0\u043e\u0437\u043d\u0430\u0447\u0430\u0432\u0430\u00a0<em>\u0438\u043b\u0438<\/em>\u00a0\u0438\u043b\u0438\u00a0<em>\u043c\u0435\u0436\u0434\u0443<\/em>. \u0412 \u043f\u0440\u043e\u0442\u0438\u0432\u0435\u043d \u0441\u043b\u0443\u0447\u0430\u0439 \u0438\u043c\u0430 \u0441\u0438\u043b\u043d\u0430 \u0442\u0435\u043d\u0434\u0435\u043d\u0446\u0438\u044f \u043a\u044a\u043c\u00a0<em>\u043a\u044a\u043c<\/em>\u00a0\u0432\u044a\u0437\u043f\u0440\u0438\u0435\u043c\u0435\u0442\u0435 \u0437\u043d\u0430\u0447\u0435\u043d\u0438\u0435\u0442\u043e \u043d\u0430\u00a0<em>e<\/em>.<\/p>\n<h2>\u0414\u0440\u0443\u0436\u0431\u0430 \u0441 \u044f\u043f\u043e\u043d\u0441\u043a\u0430\u0442\u0430 \u0447\u0430\u0441\u0442\u0438\u0446\u0430 \u0434\u043e<\/h2>\n<p>\u0412 \u043d\u044f\u043a\u043e\u0438 \u0438\u0437\u0440\u0435\u0447\u0435\u043d\u0438\u044f, \u043a\u043e\u0433\u0430\u0442\u043e \u0447\u0430\u0441\u0442\u0438\u0446\u0430\u0442\u0430\u00a0<em>\u043a\u044a\u043c<\/em>\u00a0\u0441\u0435 \u043f\u043e\u044f\u0432\u044f\u0432\u0430 \u043c\u0435\u0436\u0434\u0443 \u0438\u043c\u0435\u043d\u0430 \u0438\u043b\u0438 \u043c\u0435\u0441\u0442\u043e\u0438\u043c\u0435\u043d\u0438\u044f, \u043e\u0437\u043d\u0430\u0447\u0430\u0432\u0430 \u0434\u0440\u0443\u0433\u0430\u0440\u0441\u0442\u0432\u043e \u0438 \u043c\u043e\u0436\u0435 \u0434\u0430 \u0441\u0435 \u043f\u0440\u0435\u0432\u0435\u0434\u0435 \u043a\u0430\u0442\u043e\u00a0<em>\u0441<\/em>.<\/p>\n<p><strong>\u041f\u0440\u0438\u043c\u0435\u0440\u0438:<\/strong><\/p>\n<p><acronym title=\"Kinou wa, otouto to kawa e oyogi ni ikimashita.\">\u6628\u65e5\u306f\u3001\u5f1f<span style=\"color: #ff6600\">\u3068<\/span>\u5ddd\u3078\u6cf3\u304e\u306b\u884c\u304d\u307e\u3057\u305f\u3002<\/acronym><\/p>\n<p><em>\u0412\u0447\u0435\u0440\u0430 \u043f\u043b\u0443\u0432\u0430\u0445 \u0432 \u0440\u0435\u043a\u0430\u0442\u0430\u00a0<span style=\"color: #ff6600\">\u0441<\/span>\u00a0\u0431\u0440\u0430\u0442 \u043c\u0438.<\/em><\/p>\n<p><acronym title=\"Ashita kono mondai ni tsuite, sensei to hanasu tsumori desu.\">\u660e\u65e5\u3053\u306e\u554f\u984c\u306b\u3064\u3044\u3066\u3001\u5148\u751f<span style=\"color: #ff6600\">\u3068<\/span>\u8a71\u3059\u3064\u3082\u308a\u3067\u3059\u3002<\/acronym><\/p>\n<p><em>\u0429\u0435 \u043e\u0431\u0441\u044a\u0434\u044f \u0442\u043e\u0437\u0438 \u043f\u0440\u043e\u0431\u043b\u0435\u043c \u0443\u0442\u0440\u0435\u00a0<span style=\"color: #ff6600\">\u0441<\/span>\u00a0\u0443\u0447\u0438\u0442\u0435\u043b\u044f\/\u0438\u043d\u0441\u0442\u0440\u0443\u043a\u0442\u043e\u0440\u0430.<\/em><\/p>\n<h2>\u0421\u044a\u0447\u0435\u0442\u0430\u0432\u0430\u043d\u0435 \u043d\u0430 \u0447\u0430\u0441\u0442\u0438\u0446\u0430\u0442\u0430 to \u0441 \u044f\u043f\u043e\u043d\u0441\u043a\u0438 \u0433\u043b\u0430\u0433\u043e\u043b\u0438<\/h2>\n<p>\u0415\u0434\u043d\u043e \u043e\u0442 \u043d\u0430\u0439-\u0438\u043d\u0442\u0435\u0440\u0435\u0441\u043d\u0438\u0442\u0435 \u043d\u0435\u0449\u0430, \u043a\u043e\u0438\u0442\u043e \u043e\u0442\u043a\u0440\u0438\u0445 \u0437\u0430 \u0447\u0430\u0441\u0442\u0438\u0446\u0438\u0442\u0435\u00a0<em>\u043a\u044a\u043c<\/em>\u0435 \u0444\u0430\u043a\u0442\u044a\u0442, \u0447\u0435 \u043c\u043e\u0436\u0435 \u0434\u0430 \u0441\u0435 \u043a\u043e\u043c\u0431\u0438\u043d\u0438\u0440\u0430 \u0441\u00a0<a title=\"\u042f\u043f\u043e\u043d\u0441\u043a\u0438 \u0433\u043b\u0430\u0433\u043e\u043b\u0438\" href=\"https:\/\/comoaprenderjapones.net\/bg\/%d1%8f%d0%bf%d0%be%d0%bd%d1%81%d0%ba%d0%b8-%d0%b3%d0%bb%d0%b0%d0%b3%d0%be%d0%bb%d0%b8\/\">\u042f\u043f\u043e\u043d\u0441\u043a\u0438 \u0433\u043b\u0430\u0433\u043e\u043b\u0438<\/a>\u00a0\u0434\u0430 \u0438\u0437\u0440\u0430\u0437\u044f\u0432\u0430\u0442\u0435 \u043c\u0438\u0441\u043b\u0438 \u0438 \u0434\u0435\u0439\u0441\u0442\u0432\u0438\u044f \u0437\u0430 \u0434\u0440\u0443\u0433\u0438 \u0445\u043e\u0440\u0430 \u0438\u043b\u0438 \u0437\u0430 \u043d\u0435\u0449\u043e.<\/p>\n<p><strong>\u041f\u0440\u0438\u043c\u0435\u0440\u0438:<\/strong><\/p>\n<p><acronym title=\"kinou ga yasumi datta to omou\">\u6628\u65e5\u304c\u4f11\u307f\u3060\u3063\u305f<span style=\"color: #ff6600\">\u3068\u601d\u3046<\/span>\u3002<\/acronym><\/p>\n<p><em><span style=\"color: #ff6600\">\u041f\u043e\u043c\u0438\u0441\u043b\u0438\u0445 \u0441\u0438.<\/span>\u00a0\u0432\u0447\u0435\u0440\u0430 \u0431\u0435\u0448\u0435 \u043e\u0444\u0438\u0446\u0438\u0430\u043b\u0435\u043d \u043f\u0440\u0430\u0437\u043d\u0438\u043a.<\/em><\/p>\n<p><acronym title=\"kanojo wa otoko ga shinjimasen toiu.\">\u5f7c\u5973\u306f\u7537\u304c\u4fe1\u3058\u307e\u305b\u3093<span style=\"color: #ff6600\">\u3068\u8a00\u3046<\/span>\u3002<\/acronym><\/p>\n<p><em>\u041d\u0435\u0439\u043d\u0438\u044f\u0442\u00a0<span style=\"color: #ff6600\">\u043a\u0430\u0437\u0430<\/span>\u00a0\u043d\u0435 \u0432\u044f\u0440\u0432\u0430 \u0432 \u043c\u044a\u0436\u0435\u0442\u0435.<\/em><\/p>\n<p>\u0421\u043f\u0438\u0441\u044a\u043a\u044a\u0442 \u0441 \u043a\u043e\u043c\u0431\u0438\u043d\u0430\u0446\u0438\u0438 \u043f\u043e-\u0434\u043e\u043b\u0443 \u0435 \u043d\u0430\u0439-\u0447\u0435\u0441\u0442\u043e \u0441\u0440\u0435\u0449\u0430\u043d\u0438\u044f\u0442 \u0432 \u044f\u043f\u043e\u043d\u0441\u043a\u0438\u044f \u0435\u0437\u0438\u043a:<\/p>\n<p><acronym title=\"\u0434\u0430 \u0445\u0430\u043d\u0430\u0441\u0443\">\u3068\u8a71\u3059<\/acronym>\u00a0(\u041a\u0430\u0436\u0438, \u043a\u0430\u0436\u0438, \u0447\u0435...)<\/p>\n<p><acronym title=\"\u043a\u044a\u043c iu\">\u3068\u8a00\u3046<\/acronym>\u00a0(\u041a\u0430\u0442\u043e \u043a\u0430\u0437\u0432\u0430\u043c \u0442\u043e\u0432\u0430...)<\/p>\n<p><acronym title=\"\u0434\u043e Kangaeru\">\u3068\u8003\u3048\u308b<\/acronym>\u00a0(\u041f\u043e\u043c\u0438\u0441\u043b\u0435\u0442\u0435 \u0437\u0430 \u0442\u043e\u0432\u0430...)<\/p>\n<p><acronym title=\"\u0437\u0430 \u043e\u043c\u043e\u0443\">\u3068\u601d\u3046<\/acronym>\u00a0(\u0414\u0430 \u043f\u043e\u043c\u0438\u0441\u043b\u0438\u043c...)<\/p>\n<p><acronym title=\"to souzou suru\">\u3068\u5275\u9020\u3059\u308b<\/acronym>\u00a0(\u041f\u0440\u0435\u0434\u0441\u0442\u0430\u0432\u0435\u0442\u0435 \u0441\u0438 \u0442\u043e\u0432\u0430...)<\/p>\n<p><acronym title=\"\u0437\u0430 wakaru\">\u3068\u5206\u304b\u308b<\/acronym>\u00a0(\u0420\u0430\u0437\u0431\u0435\u0440\u0435\u0442\u0435 \u0442\u043e\u0432\u0430...)<\/p>\n<h2>\u0417\u0430\u043a\u043b\u044e\u0447\u0435\u043d\u0438\u0435<\/h2>\n<p>\u0412\u044a\u043f\u0440\u0435\u043a\u0438 \u0447\u0435 \u0438\u043c\u0430 \u0438 \u0434\u0440\u0443\u0433\u0438 \u043f\u043e-\u0441\u043b\u043e\u0436\u043d\u0438 \u0444\u0443\u043d\u043a\u0446\u0438\u0438 \u043d\u0430 \u0447\u0430\u0441\u0442\u0438\u0446\u0438\u0442\u0435\u00a0<em>\u043a\u044a\u043c<\/em>\u041e\u043f\u0438\u0442\u0430\u0445 \u0441\u0435 \u0434\u0430 \u043e\u0431\u043e\u0431\u0449\u044f \u043d\u0430\u0439-\u043e\u0441\u043d\u043e\u0432\u043d\u043e\u0442\u043e \u0438 \u043d\u0430\u0439-\u043b\u0435\u0441\u043d\u043e\u0442\u043e \u0437\u0430 \u0440\u0430\u0437\u0431\u0438\u0440\u0430\u043d\u0435. \u0421 \u0442\u0435\u0437\u0438 \u0437\u043d\u0430\u043d\u0438\u044f \u0435 \u043f\u043e-\u043b\u0435\u0441\u043d\u043e \u0434\u0430 \u0441\u0435 \u0440\u0430\u0437\u0431\u0435\u0440\u0430\u0442 \u043f\u043e\u0432\u0435\u0447\u0435\u0442\u043e \u044f\u043f\u043e\u043d\u0441\u043a\u0438 \u0444\u0440\u0430\u0437\u0438 \u043e\u0442 \u0435\u0436\u0435\u0434\u043d\u0435\u0432\u0438\u0435\u0442\u043e.<\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>\u041d\u0430\u0443\u0447\u0435\u0442\u0435 \u043f\u043e\u0432\u0435\u0447\u0435 \u0437\u0430 \u0447\u0430\u0441\u0442\u0438\u0446\u0430\u0442\u0430 \u0422\u041e \u043d\u0430 \u044f\u043f\u043e\u043d\u0441\u043a\u0438 \u0435\u0437\u0438\u043a \u0441\u0435\u0433\u0430! \u042f\u043f\u043e\u043d\u0441\u043a\u0430\u0442\u0430 \u0447\u0430\u0441\u0442\u0438\u0446\u0430 \u0422\u041e \u0435 \u0434\u0440\u0443\u0433\u0430 \u0447\u0430\u0441\u0442\u0438\u0446\u0430, \u043a\u043e\u044f\u0442\u043e \u0435 \u043c\u043d\u043e\u0433\u043e \u0434\u043e\u0431\u0440\u0435 \u043f\u043e\u0437\u043d\u0430\u0442\u0430 \u043d\u0430 \u0438\u0437\u0443\u0447\u0430\u0432\u0430\u0449\u0438\u0442\u0435 \u044f\u043f\u043e\u043d\u0441\u043a\u0438 \u0435\u0437\u0438\u043a. \u041d\u0435\u0439\u043d\u0430\u0442\u0430 \u043d\u0430\u0439-\u0447\u0435\u0441\u0442\u043e \u0441\u0440\u0435\u0449\u0430\u043d\u0430 \u0444\u0443\u043d\u043a\u0446\u0438\u044f \u0435 \u043f\u0440\u043e\u0441\u0442\u043e \u0434\u0430 \u0441\u044a\u0435\u0434\u0438\u043d\u044f\u0432\u0430 \u0441\u043f\u0438\u0441\u044a\u0446\u0438 \u043e\u0442 \u044f\u043f\u043e\u043d\u0441\u043a\u0438 \u0441\u044a\u0449\u0435\u0441\u0442\u0432\u0438\u0442\u0435\u043b\u043d\u0438 \u0438\u043b\u0438 \u0434\u043e\u0440\u0438 \u0438\u0437\u0440\u0435\u0447\u0435\u043d\u0438\u044f. \u0417\u0430 \u0440\u0430\u0437\u043b\u0438\u043a\u0430 \u043e\u0442 \u0434\u0440\u0443\u0433\u0438 \u044f\u043f\u043e\u043d\u0441\u043a\u0438 \u0447\u0430\u0441\u0442\u0438\u0446\u0438,<\/p>","protected":false},"author":18,"featured_media":2406,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[74,70],"tags":[71,2,3],"class_list":["post-2403","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-particulas-em-japones","category-gramatica-japonesa","tag-gramatica-japonesa","tag-idioma-japones","tag-nihongo"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/comoaprenderjapones.net\/wp-content\/uploads\/2018\/07\/a-particula-to-em-japones.png?fit=600%2C600&ssl=1","jetpack-related-posts":[{"id":2370,"url":"https:\/\/comoaprenderjapones.net\/bg\/a-particula-ya-em-japones\/","url_meta":{"origin":2403,"position":0},"title":"\u0427\u0430\u0441\u0442\u0438\u0446\u0430\u0442\u0430 YA \u0432 \u044f\u043f\u043e\u043d\u0441\u043a\u0438\u044f \u0435\u0437\u0438\u043a","author":"L\u00edngua Japonesa","date":"3 de \u0444\u0435\u0432\u0440\u0443\u0430\u0440\u0438 de 2010","format":false,"excerpt":"Agora vamos ampliar seu conhecimento sobre\u00a0a part\u00edcula YA em japon\u00eas! A principal fun\u00e7\u00e3o da part\u00edcula\u00a0ya\u00a0\u00e9 simplesmente criar listas de substantivos japoneses. Dessa forma, podemos citar um conjunto de coisas existentes em algum lugar ou coisas que iremos fazer. Neste momento, muitos leitores devem estar lembrando da part\u00edcula japonesa\u00a0to, que tamb\u00e9m\u2026","rel":"","context":"In &quot;Gram\u00e1tica Japonesa&quot;","block_context":{"text":"Gram\u00e1tica Japonesa","link":"https:\/\/comoaprenderjapones.net\/bg\/gramatica-japonesa\/"},"img":{"alt_text":"A part\u00edcula YA em japon\u00eas","src":"https:\/\/i0.wp.com\/comoaprenderjapones.net\/wp-content\/uploads\/2018\/07\/a-particula-ya-em-japones.png?fit=600%2C600&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/comoaprenderjapones.net\/wp-content\/uploads\/2018\/07\/a-particula-ya-em-japones.png?fit=600%2C600&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/comoaprenderjapones.net\/wp-content\/uploads\/2018\/07\/a-particula-ya-em-japones.png?fit=600%2C600&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":1661,"url":"https:\/\/comoaprenderjapones.net\/bg\/sujeito-das-frases-em-japones\/","url_meta":{"origin":2403,"position":1},"title":"\u041f\u0440\u0435\u0434\u043c\u0435\u0442 \u043d\u0430 \u0438\u0437\u0440\u0435\u0447\u0435\u043d\u0438\u044f\u0442\u0430 \u0432 \u044f\u043f\u043e\u043d\u0441\u043a\u0438\u044f \u0435\u0437\u0438\u043a","author":"L\u00edngua Japonesa","date":"3 de \u043d\u043e\u0435\u043c\u0432\u0440\u0438 de 2009","format":false,"excerpt":"Aprenda mais sobre\u00a0o sujeito das frases em japon\u00eas no nihongo! Como j\u00e1 estudamos\u00a0a ordem das palavras nas frases em japon\u00eas, sabemos que elas possuem uma organiza\u00e7\u00e3o inversa das palavras na l\u00edngua portuguesa. Nas frases em japon\u00eas, geralmente a ordem das palavras \u00e9\u00a0sujeito\u00a0+\u00a0objeto\u00a0(predicado ou resto da frase) +\u00a0verbo. Para ficar mais\u2026","rel":"","context":"In &quot;Curso de Japon\u00eas Gr\u00e1tis&quot;","block_context":{"text":"Curso de Japon\u00eas Gr\u00e1tis","link":"https:\/\/comoaprenderjapones.net\/bg\/curso-de-japones-gratis\/"},"img":{"alt_text":"O sujeito das frases em japon\u00eas - part\u00edcula WA ","src":"https:\/\/i0.wp.com\/comoaprenderjapones.net\/wp-content\/uploads\/2015\/03\/ha-150x150.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":2820,"url":"https:\/\/comoaprenderjapones.net\/bg\/particula-mo-em-japones\/","url_meta":{"origin":2403,"position":2},"title":"\u0427\u0430\u0441\u0442\u0438\u0446\u0430\u0442\u0430 MO \u043d\u0430 \u044f\u043f\u043e\u043d\u0441\u043a\u0438 \u0435\u0437\u0438\u043a","author":"L\u00edngua Japonesa","date":"6 de \u044f\u043d\u0443\u0430\u0440\u0438 de 2010","format":false,"excerpt":"Em japon\u00eas, a fun\u00e7\u00e3o mais comum da part\u00edcula\u00a0mo\u00a0\u00e9 indicar uma esp\u00e9cie de similaridade entre palavras da mesma senten\u00e7a. Segundo a\u00a0gram\u00e1tica japonesa, a part\u00edcula\u00a0mo\u00a0pode substituir outras part\u00edculas em frases paralelas, colocando duas palavras em p\u00e9 de igualdade ou assumindo o mesmo significado de palavras como\u00a0tamb\u00e9m,\u00a0bem como,\u00a0t\u00e3o...quanto\u00a0e outras com o mesmo significado.\u2026","rel":"","context":"In &quot;Gram\u00e1tica Japonesa&quot;","block_context":{"text":"Gram\u00e1tica Japonesa","link":"https:\/\/comoaprenderjapones.net\/bg\/gramatica-japonesa\/"},"img":{"alt_text":"A part\u00edcula mo - \u3082","src":"https:\/\/i0.wp.com\/comoaprenderjapones.net\/wp-content\/uploads\/2010\/01\/particula-MO-em-japones.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/comoaprenderjapones.net\/wp-content\/uploads\/2010\/01\/particula-MO-em-japones.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/comoaprenderjapones.net\/wp-content\/uploads\/2010\/01\/particula-MO-em-japones.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/comoaprenderjapones.net\/wp-content\/uploads\/2010\/01\/particula-MO-em-japones.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/comoaprenderjapones.net\/wp-content\/uploads\/2010\/01\/particula-MO-em-japones.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":1637,"url":"https:\/\/comoaprenderjapones.net\/bg\/gramatica-japonesa-fundamental\/","url_meta":{"origin":2403,"position":3},"title":"\u041e\u0441\u043d\u043e\u0432\u0438 \u043d\u0430 \u044f\u043f\u043e\u043d\u0441\u043a\u0430\u0442\u0430 \u0433\u0440\u0430\u043c\u0430\u0442\u0438\u043a\u0430","author":"L\u00edngua Japonesa","date":"7 de \u043d\u043e\u0435\u043c\u0432\u0440\u0438 de 2009","format":false,"excerpt":"Aprenda mais sobre a\u00a0gram\u00e1tica japonesa fundamental para voc\u00ea estudante de nihongo! No artigo de hoje, vamos entender alguns dos fundamentos da l\u00edngua japonesa, compreendendo a forma\u00e7\u00e3o de frases simples. Gram\u00e1tica japonesa fundamental O conte\u00fado de hoje tamb\u00e9m ajudar\u00e1 a entender melhor tudo o que j\u00e1 aprendemos nos artigos anteriores. Apesar\u2026","rel":"","context":"In &quot;Curso de Japon\u00eas Gr\u00e1tis&quot;","block_context":{"text":"Curso de Japon\u00eas Gr\u00e1tis","link":"https:\/\/comoaprenderjapones.net\/bg\/curso-de-japones-gratis\/"},"img":{"alt_text":"estudando japones","src":"https:\/\/i0.wp.com\/comoaprenderjapones.net\/wp-content\/uploads\/2014\/09\/estudando_japones.jpg?fit=450%2C300&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1729,"url":"https:\/\/comoaprenderjapones.net\/bg\/particulas-basicas-em-japones\/","url_meta":{"origin":2403,"position":4},"title":"\u041e\u0441\u043d\u043e\u0432\u043d\u0438 \u0447\u0430\u0441\u0442\u0438\u0446\u0438 \u0432 \u044f\u043f\u043e\u043d\u0441\u043a\u0438\u044f \u0435\u0437\u0438\u043a","author":"L\u00edngua Japonesa","date":"15 de \u043d\u043e\u0435\u043c\u0432\u0440\u0438 de 2009","format":false,"excerpt":"Conhe\u00e7a e aprenda mais sobre\u00a0as part\u00edculas b\u00e1sicas em japon\u00eas! As part\u00edculas s\u00e3o pequenos elementos gramaticais, geralmente escritas usando uma \u00fanica s\u00edlaba do\u00a0alfabeto japon\u00eas em hiragana, e n\u00e3o possuem uma tradu\u00e7\u00e3o espec\u00edfica. A fun\u00e7\u00e3o das part\u00edculas em japon\u00eas \u00e9 puramente gramatical, servindo como uma marca para identificar a fun\u00e7\u00e3o das palavras\u2026","rel":"","context":"In &quot;Curso de Japon\u00eas Gr\u00e1tis&quot;","block_context":{"text":"Curso de Japon\u00eas Gr\u00e1tis","link":"https:\/\/comoaprenderjapones.net\/bg\/curso-de-japones-gratis\/"},"img":{"alt_text":"As part\u00edculas b\u00e1sicas em japon\u00eas - \u5f7c\u306f\u65e5\u672c\u4eba\u3067\u3059\u3002","src":"https:\/\/i0.wp.com\/comoaprenderjapones.net\/wp-content\/uploads\/2009\/11\/particulas-basicas-em-japones.png?fit=500%2C400&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1735,"url":"https:\/\/comoaprenderjapones.net\/bg\/particulas-para-final-de-frases-em-japones\/","url_meta":{"origin":2403,"position":5},"title":"\u0427\u0430\u0441\u0442\u0438\u0446\u0438 \u0437\u0430 \u043a\u0440\u0430\u0439 \u043d\u0430 \u0438\u0437\u0440\u0435\u0447\u0435\u043d\u0438\u044f\u0442\u0430 \u0432 \u044f\u043f\u043e\u043d\u0441\u043a\u0438\u044f \u0435\u0437\u0438\u043a","author":"L\u00edngua Japonesa","date":"3 de \u043d\u043e\u0435\u043c\u0432\u0440\u0438 de 2009","format":false,"excerpt":"Saiba mais sobre as\u00a0Part\u00edculas para o final de frases em japon\u00eas! Eu estava estudando a finaliza\u00e7\u00e3o de frases em japon\u00eas usando part\u00edculas e descobri algumas part\u00edculas b\u00e1sicas e bem interessantes. Part\u00edculas para o final de frases em japon\u00eas Apesar de possu\u00edrem significados semelhantes, essas part\u00edculas japonesas possuem caracter\u00edsticas bem particulares.\u2026","rel":"","context":"In &quot;Curso de Japon\u00eas Gr\u00e1tis&quot;","block_context":{"text":"Curso de Japon\u00eas Gr\u00e1tis","link":"https:\/\/comoaprenderjapones.net\/bg\/curso-de-japones-gratis\/"},"img":{"alt_text":"Part\u00edculas para o final de frases em japon\u00eas","src":"https:\/\/i0.wp.com\/comoaprenderjapones.net\/wp-content\/uploads\/2018\/03\/particulas-para-final-de-frases-em-japones.png?fit=500%2C400&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/comoaprenderjapones.net\/bg\/wp-json\/wp\/v2\/posts\/2403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comoaprenderjapones.net\/bg\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comoaprenderjapones.net\/bg\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comoaprenderjapones.net\/bg\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/comoaprenderjapones.net\/bg\/wp-json\/wp\/v2\/comments?post=2403"}],"version-history":[{"count":0,"href":"https:\/\/comoaprenderjapones.net\/bg\/wp-json\/wp\/v2\/posts\/2403\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comoaprenderjapones.net\/bg\/wp-json\/wp\/v2\/media\/2406"}],"wp:attachment":[{"href":"https:\/\/comoaprenderjapones.net\/bg\/wp-json\/wp\/v2\/media?parent=2403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comoaprenderjapones.net\/bg\/wp-json\/wp\/v2\/categories?post=2403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comoaprenderjapones.net\/bg\/wp-json\/wp\/v2\/tags?post=2403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}