{"id":1278,"date":"2009-11-02T08:53:26","date_gmt":"2009-11-02T10:53:26","guid":{"rendered":"https:\/\/comoaprenderjapones.net\/?p=1278"},"modified":"2018-03-02T00:47:20","modified_gmt":"2018-03-02T03:47:20","slug":"katakana-vokale","status":"publish","type":"post","link":"https:\/\/comoaprenderjapones.net\/de\/vogais-do-katakana\/","title":{"rendered":"die Vokale von Katakana"},"content":{"rendered":"<div class=\"5057f5bb79852941df3b6d5de6744a76\" data-index=\"2\" style=\"float: none; margin:0px;\">\n<script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-0652292147574552\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<!-- Ads responsivo Inicio Post CAJap -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-0652292147574552\"\r\n     data-ad-slot=\"3298668993\"\r\n     data-ad-format=\"auto\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p><em>Lern es\u00a0<strong>die Vokale von Katakana<\/strong> und Ihre Schlagreihenfolge!<\/em><\/p>\n<p>Wie in den japanischen Alphabet-Lektionen in Hiragana erw\u00e4hnt, ist die Methode, die ich zum Lernen verwende, die gleiche wie in B\u00fcchern wie <a href=\"https:\/\/comoaprenderjapones.net\/de\/in\/kanjis-mnemonics\/\" target=\"_blank\" rel=\"noopener\">Kanji-Mnemonik<\/a> und <a href=\"https:\/\/comoaprenderjapones.net\/de\/in\/remember-the-kanji\/\" target=\"_blank\" rel=\"noopener\">Denken Sie an das Kanji<\/a>. Meine Aufgabe bestand lediglich darin, die Technik an meine Realit\u00e4t anzupassen, da die B\u00fccher auf Englisch sind und der Autor f\u00fcr Sprecher dieser Sprache schreibt. Wenn Sie es schwierig finden, versuchen Sie, Ihre eigene Geschichte zu erfinden.<span id=\"more-13\"><\/span><\/p>\n<p>Der einfachste und schnellste Weg, japanische Schriftzeichen zu lernen, egal ob es sich um Hiragana, Katakana oder Kanji handelt, besteht darin, sie in Teile zu zerlegen und zu versuchen, sie zu finden <a href=\"https:\/\/comoaprenderjapones.net\/de\/fan-art-methode\/\">Zeichnungen unseres Alltags<\/a>. Nachdem Sie diese Zeichnungen gefunden haben, versuchen Sie, eine Geschichte mit ihnen zu erfinden und die Bilder in Ihrem Kopf zu sehen (Fantasie). Mit der Zeit werden Sie feststellen, dass Sie sich beim Betrachten des orientalischen Schriftzeichens schnell an den erw\u00e4hnten Vokal erinnern und umgekehrt.<\/p>\n<h2>die Vokale von Katakana<\/h2>\n<p>\u30a2 = A<br \/>\nIch wei\u00df nicht, ob Sie dasselbe sehen k\u00f6nnen wie ich, aber ich kann eine Waffe sehen, die von einer Person gef\u00fchrt wird. Eine Art Revolver mit langem Griff. Wenn Sie das nicht k\u00f6nnen, nutzen Sie Ihre Vorstellungskraft und versuchen Sie, etwas anderes zu sehen. Unten sehen Sie die Abfolge der Striche zum Zeichnen des Symbols.<\/p>\n<p class=\"align-center\"><img decoding=\"async\" class=\"aligncenter wp-image-1279 size-full\" title=\"Katakana-Schlagreihenfolge A\" src=\"https:\/\/comoaprenderjapones.net\/wp-content\/uploads\/2018\/03\/katakana-a-ordem-dos-tracos.jpg\" alt=\"Katakana-Schlagreihenfolge A\" width=\"273\" height=\"110\" \/><\/p>\n<p>\u30a4 = ich<br \/>\nStellen Sie sich nun vor, Sie schreiben den Buchstaben \u201ei\u201c. Dann rutscht Ihre Hand ab und erzeugt am Ende dieses Bild eines schiefen \u201eT\u201c. Einfach, nein? Es folgt die Abfolge der Striche:<\/p>\n<p class=\"align-center\"><img decoding=\"async\" class=\"aligncenter wp-image-1280 size-full\" title=\"Katakana I Strichreihenfolge\" src=\"https:\/\/comoaprenderjapones.net\/wp-content\/uploads\/2018\/03\/katakana-i-ordem-dos-tracos.jpg\" alt=\"Katakana I Strichreihenfolge\" width=\"279\" height=\"128\" \/><\/p>\n<p>\u30a6 = U<br \/>\nDas \u201eu\u201c-Katakana sieht aus wie ein Einhornkopf-Design. Es ist, als w\u00fcrde er den Kopf heben und das Horn ist das obere Mittelmerkmal. Die Reihenfolge der Striche ist wie folgt:<\/p>\n<p class=\"align-center\"><img decoding=\"async\" class=\"aligncenter wp-image-1281 size-full\" title=\"Katakana U Schlagreihenfolge\" src=\"https:\/\/comoaprenderjapones.net\/wp-content\/uploads\/2018\/03\/katakana-u-ordem-dos-tracos.jpg\" alt=\"Katakana U Schlagreihenfolge\" width=\"320\" height=\"118\" srcset=\"https:\/\/comoaprenderjapones.net\/wp-content\/uploads\/2018\/03\/katakana-u-ordem-dos-tracos.jpg 320w, https:\/\/comoaprenderjapones.net\/wp-content\/uploads\/2018\/03\/katakana-u-ordem-dos-tracos-300x111.jpg 300w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/><\/p>\n<p><br \/>\n\u30a8 = E<br \/>\nDer Vokal \u201ee\u201c ist f\u00fcr mich ein Seilt\u00e4nzer mit einem Stock auf dem Kopf, der auf dem Banba-Seil geht. Das zentrale Merkmal ist der Balanceakt. Hier ist die Reihenfolge der Striche:<\/p>\n<p class=\"align-center\"><img decoding=\"async\" class=\"aligncenter wp-image-1282 size-full\" title=\"Katakana-Schlagreihenfolge E\" src=\"https:\/\/comoaprenderjapones.net\/wp-content\/uploads\/2018\/03\/katakana-e-ordem-dos-tracos.jpg\" alt=\"Katakana-Schlagreihenfolge E\" width=\"320\" height=\"90\" srcset=\"https:\/\/comoaprenderjapones.net\/wp-content\/uploads\/2018\/03\/katakana-e-ordem-dos-tracos.jpg 320w, https:\/\/comoaprenderjapones.net\/wp-content\/uploads\/2018\/03\/katakana-e-ordem-dos-tracos-300x84.jpg 300w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/><\/p>\n<p>\u30aa = O<br \/>\nDas \u201eo\u201c des Katakana ist wie die Vertiefung eines Indianers. Diese H\u00fctten, die mitten in den W\u00e4ldern stehen. Beim Katakana \u201eo\u201c ist die H\u00fctte etwas nach rechts gedreht. Siehe die Reihenfolge der Striche:<\/p>\n<p class=\"align-center\"><img decoding=\"async\" class=\"aligncenter wp-image-1283 size-full\" title=\"Katakana-Schlagreihenfolge O\" src=\"https:\/\/comoaprenderjapones.net\/wp-content\/uploads\/2018\/03\/katakana-o-ordem-dos-tracos.jpg\" alt=\"Katakana-Schlagreihenfolge O\" width=\"320\" height=\"100\" srcset=\"https:\/\/comoaprenderjapones.net\/wp-content\/uploads\/2018\/03\/katakana-o-ordem-dos-tracos.jpg 320w, https:\/\/comoaprenderjapones.net\/wp-content\/uploads\/2018\/03\/katakana-o-ordem-dos-tracos-300x94.jpg 300w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/><\/p>\n<h2>Japanische Kalligrafie-\u00dcbung<\/h2>\n<p>W\u00e4hle aus <a href=\"https:\/\/comoaprenderjapones.net\/de\/katakana-volltisch\/\">Japanische Alphabetsymbole<\/a> und klicken Sie auf die Schaltfl\u00e4che Generieren auf der <a href=\"https:\/\/comoaprenderjapones.net\/de\/in\/imprimir-para-treinar-kanas-e-kanjis\/\" target=\"_blank\" rel=\"noopener\">Arbeitsblatt f\u00fcr die Kana- und Kanji-\u00dcbung<\/a> . Daraufhin \u00f6ffnet sich ein neues Fenster mit der Datei zum Drucken. Dann einfach ausdrucken, die grauen Katakana-Symbole abdecken und dann versuchen, es selbst zu schreiben. Einfach ausdrucken und \u00fcben!<\/p>\n<table style=\"height: 38px\" border=\"0\" width=\"383\" cellspacing=\"2\" cellpadding=\"2\">\n<tbody>\n<tr>\n<td align=\"left\" valign=\"middle\">\u30a2<\/td>\n<td align=\"left\" valign=\"middle\">\u30a4<\/td>\n<td align=\"left\" valign=\"middle\">\u30a6<\/td>\n<td align=\"left\" valign=\"middle\">\u30a8<\/td>\n<td align=\"left\" valign=\"middle\">\u30aa<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Lernen Sie Katakana-Vokale und ihre Strichfolge! Wie in den japanischen Alphabet-Lektionen in Hiragana erw\u00e4hnt, ist die Methode, die ich zum Lernen verwende, die gleiche wie in B\u00fcchern wie Kanjis Mnemonics<\/p>","protected":false},"author":18,"featured_media":1285,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46,48],"tags":[16,52],"class_list":["post-1278","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alfabeto-japones","category-alfabeto-japones-katakana","tag-alfabeto-japones","tag-katakana","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/comoaprenderjapones.net\/de\/wp-json\/wp\/v2\/posts\/1278","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comoaprenderjapones.net\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comoaprenderjapones.net\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comoaprenderjapones.net\/de\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/comoaprenderjapones.net\/de\/wp-json\/wp\/v2\/comments?post=1278"}],"version-history":[{"count":0,"href":"https:\/\/comoaprenderjapones.net\/de\/wp-json\/wp\/v2\/posts\/1278\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comoaprenderjapones.net\/de\/wp-json\/wp\/v2\/media\/1285"}],"wp:attachment":[{"href":"https:\/\/comoaprenderjapones.net\/de\/wp-json\/wp\/v2\/media?parent=1278"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comoaprenderjapones.net\/de\/wp-json\/wp\/v2\/categories?post=1278"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comoaprenderjapones.net\/de\/wp-json\/wp\/v2\/tags?post=1278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}