{"id":1311,"date":"2009-11-02T09:19:35","date_gmt":"2009-11-02T11:19:35","guid":{"rendered":"https:\/\/comoaprenderjapones.net\/?p=1311"},"modified":"2018-03-02T21:44:40","modified_gmt":"2018-03-03T00:44:40","slug":"familie-do-t-in-katakana","status":"publish","type":"post","link":"https:\/\/comoaprenderjapones.net\/de\/familia-do-t-em-katakana\/","title":{"rendered":"Die Familie T in Katakana"},"content":{"rendered":"<div class=\"5057f5bb79852941df3b6d5de6744a76\" data-index=\"2\" style=\"float: none; margin:0px;\">\n<script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-0652292147574552\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<!-- Ads responsivo Inicio Post CAJap -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-0652292147574552\"\r\n     data-ad-slot=\"3298668993\"\r\n     data-ad-format=\"auto\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p><em>Treffen <strong>Ts Familie in Katakana<\/strong> und die Strichreihenfolge in Ihrem Schreiben!<\/em><\/p>\n<h2>Die Familie T in Katakana<\/h2>\n<p>\u30bf = TA<br \/>\nDas Katakana TA ist ein schiefer Gro\u00dfbuchstabe A.<\/p>\n<p class=\"align-center\"><img decoding=\"async\" class=\"aligncenter wp-image-1313 size-full\" title=\"Katakana ta Schlagreihenfolge\" src=\"https:\/\/comoaprenderjapones.net\/wp-content\/uploads\/2009\/11\/katakana-ta-ordem-dos-tracos.jpg\" alt=\"Katakana ta Schlagreihenfolge\" width=\"286\" height=\"69\" \/><\/p>\n<p>\u30c1 = TCHI<br \/>\nWas sehen wir hier? Ein Schwert mit Hut!<\/p>\n<p class=\"align-center\"><img decoding=\"async\" class=\"aligncenter wp-image-1314 size-full\" title=\"Reihenfolge der Katakana-Chi-Schl\u00e4ge\" src=\"https:\/\/comoaprenderjapones.net\/wp-content\/uploads\/2009\/11\/katakana-chi-ordem-dos-tracos.jpg\" alt=\"Reihenfolge der Katakana-Chi-Schl\u00e4ge\" width=\"286\" height=\"69\" \/><\/p>\n<p>\u30c4 = TSU<br \/>\nIch gestehe, dass dieser sehr schwer zu lernen war. DAS <a href=\"https:\/\/comoaprenderjapones.net\/de\/familie-von-s-in-katakana\/\">Katakana \u30b7(shi)<\/a> und \u30c4(tsu) sind sich sehr \u00e4hnlich. Versuchen Sie sich in diesem Fall das L\u00e4cheln eines Fotografen vorzustellen, bevor er von einem Tsunami getroffen wird.<\/p>\n<p class=\"align-center\"><img decoding=\"async\" class=\"aligncenter wp-image-1315 size-full\" title=\"Reihenfolge der Katakana-Tsu-Schl\u00e4ge\" src=\"https:\/\/comoaprenderjapones.net\/wp-content\/uploads\/2009\/11\/katakana-tsu-ordem-dos-tracos.jpg\" alt=\"Reihenfolge der Katakana-Tsu-Schl\u00e4ge\" width=\"311\" height=\"69\" srcset=\"https:\/\/comoaprenderjapones.net\/wp-content\/uploads\/2009\/11\/katakana-tsu-ordem-dos-tracos.jpg 311w, https:\/\/comoaprenderjapones.net\/wp-content\/uploads\/2009\/11\/katakana-tsu-ordem-dos-tracos-300x67.jpg 300w\" sizes=\"(max-width: 311px) 100vw, 311px\" \/><\/p>\n<p><br \/>\n\u30c6 = TE<br \/>\nDas TE-Katakana ist nicht schief wie das Hiragana, aber es tr\u00e4gt einen Hut.<\/p>\n<p class=\"align-center\"><img decoding=\"async\" class=\"aligncenter wp-image-1316 size-full\" title=\"Katakana te Schlagreihenfolge\" src=\"https:\/\/comoaprenderjapones.net\/wp-content\/uploads\/2009\/11\/katakana-te-ordem-dos-tracos.jpg\" alt=\"Katakana te Schlagreihenfolge\" width=\"271\" height=\"69\" \/><\/p>\n<p>\u30c8 = ZU<br \/>\nDas fiel mir leicht. Er ist nur ein Stock aus einem Ast.<\/p>\n<p class=\"align-center\"><img decoding=\"async\" class=\"aligncenter wp-image-1317 size-full\" src=\"https:\/\/comoaprenderjapones.net\/wp-content\/uploads\/2009\/11\/katakana-to-ordem-dos-tracos.jpg\" alt=\"Reihenfolge der Katakana-Schl\u00e4ge bis\" width=\"168\" height=\"69\" \/><\/p>\n<h2>Japanische Kalligrafie-\u00dcbung<\/h2>\n<p>W\u00e4hle aus\u00a0<a href=\"https:\/\/comoaprenderjapones.net\/de\/alphabet-japanisch-hiragana-und-katakana\/\">Japanische Alphabetsymbole<\/a>\u00a0und klicken Sie auf die Schaltfl\u00e4che Generieren auf der\u00a0<a href=\"https:\/\/comoaprenderjapones.net\/de\/in\/imprimir-para-treinar-kanas-e-kanjis\/\" target=\"_blank\" rel=\"noopener\">Arbeitsblatt f\u00fcr die Kana- und Kanji-\u00dcbung<\/a>\u00a0. Daraufhin \u00f6ffnet sich ein neues Fenster mit der Datei zum Drucken. Dann einfach ausdrucken, die grauen Katakana-Symbole abdecken und dann versuchen, es selbst zu schreiben. Einfach ausdrucken und \u00fcben!<\/p>\n<table style=\"height: 35px\" border=\"0\" width=\"330\" cellspacing=\"2\" cellpadding=\"2\">\n<tbody>\n<tr>\n<td align=\"left\" valign=\"middle\">\u30bf<\/td>\n<td align=\"left\" valign=\"middle\">\u30c1<\/td>\n<td align=\"left\" valign=\"middle\">\u30c4<\/td>\n<td align=\"left\" valign=\"middle\">\u30c6<\/td>\n<td align=\"left\" valign=\"middle\">\u30c8<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Lernen Sie die T-Familie in Katakana und die Strichreihenfolge in Ihrem Schreiben kennen! Die T-Familie in Katakana \u30bf = TA Das Katakana TA ist ein schiefer Gro\u00dfbuchstabe A.\u30c1 =<\/p>","protected":false},"author":18,"featured_media":1320,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46,48],"tags":[16,52],"class_list":["post-1311","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alfabeto-japones","category-alfabeto-japones-katakana","tag-alfabeto-japones","tag-katakana","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/comoaprenderjapones.net\/de\/wp-json\/wp\/v2\/posts\/1311","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comoaprenderjapones.net\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comoaprenderjapones.net\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comoaprenderjapones.net\/de\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/comoaprenderjapones.net\/de\/wp-json\/wp\/v2\/comments?post=1311"}],"version-history":[{"count":0,"href":"https:\/\/comoaprenderjapones.net\/de\/wp-json\/wp\/v2\/posts\/1311\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comoaprenderjapones.net\/de\/wp-json\/wp\/v2\/media\/1320"}],"wp:attachment":[{"href":"https:\/\/comoaprenderjapones.net\/de\/wp-json\/wp\/v2\/media?parent=1311"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comoaprenderjapones.net\/de\/wp-json\/wp\/v2\/categories?post=1311"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comoaprenderjapones.net\/de\/wp-json\/wp\/v2\/tags?post=1311"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}