{"id":2403,"date":"2010-01-27T09:00:35","date_gmt":"2010-01-27T11:00:35","guid":{"rendered":"https:\/\/comoaprenderjapones.net\/?p=2403"},"modified":"2018-07-01T17:12:05","modified_gmt":"2018-07-01T20:12:05","slug":"the-particle-to-en-japonais","status":"publish","type":"post","link":"https:\/\/comoaprenderjapones.net\/fr\/a-particula-to-em-japones\/","title":{"rendered":"La particule TO en japonais"},"content":{"rendered":"<div class=\"d5c332bdcbd3300d2a784003ec0610c8\" data-index=\"2\" style=\"float: none; margin:0px;\">\n<script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-0652292147574552\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<!-- Ads responsivo Inicio Post CAJap -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-0652292147574552\"\r\n     data-ad-slot=\"3298668993\"\r\n     data-ad-format=\"auto\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p><em>En savoir plus sur <strong>la particule TO en japonais<\/strong>!<\/em><\/p>\n<p>la particule japonaise\u00a0<em>je suis\u00a0<\/em>est une autre particule bien connue des \u00e9tudiants japonais. Sa fonction la plus courante consiste simplement \u00e0 dresser des listes de\u00a0<a title=\"Noms japonais\" href=\"https:\/\/comoaprenderjapones.net\/fr\/noms-en-japonais\/\">noms japonais<\/a>\u00a0ou m\u00eame des phrases.<\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"alignleft size-full wp-image-2405\" src=\"https:\/\/i0.wp.com\/comoaprenderjapones.net\/wp-content\/uploads\/2018\/07\/particula-to-em-japones.gif?resize=130%2C130&#038;ssl=1\" alt=\"particule en japonais\" width=\"130\" height=\"130\" \/><\/p>\n<p>contrairement aux autres\u00a0<a title=\"Particules japonaises\" href=\"https:\/\/comoaprenderjapones.net\/fr\/particules-en-japonais-2\/\">particules japonaises<\/a>, la particule\u00a0<em>je suis<\/em>\u00a0r\u00e9pertorie toujours les \u00e9l\u00e9ments de mani\u00e8re objective, en indiquant tous les \u00e9l\u00e9ments existant dans une situation donn\u00e9e.<\/p>\n<h2>Joindre des mots avec la particule pour<\/h2>\n<p>Joindre des mots \u00e0 la particule\u00a0<em>je suis<\/em>, il suffit d&#039;ajouter la particule entre les mots qui composent la liste.<\/p>\n<p><strong>Exemples:<\/strong><\/p>\n<p><acronym title=\"inu \u00e0 neko ga teeburu no shita ni imasu.\">??<span style=\"color: #ff6600\">??<\/span>\u732b\u304c\u30c6\u30fc\u30d6\u30eb\u306e\u4e0b\u306b\u3044\u307e\u3059\u3002<\/acronym><\/p>\n<p><em>avoir un chien\u00a0<span style=\"color: #ff6600\">et<\/span>\u00a0un chat sous la table.<\/em><\/p>\n<p><acronym title=\"ringo to budoo ga teeburu no ue ni arimasu.\">??<span style=\"color: #ff6600\">??<\/span>\u3076\u3069\u3046\u304c\u30c6\u30fc\u30d6\u30eb\u306e\u4e0a\u306b\u3042\u308a\u307e\u3059\u3002<\/acronym><\/p>\n<p><acronym title=\"akai ringo \u00e0 midori \u00e0 budoo ga teeburu no ue ni arimasu.\">\u8d64\u3044\u308a\u3093\u3054<span style=\"color: #ff6600\">??<\/span>\u7dd1\u306e\u3076\u3069\u3046\u3082\u30c6\u30fc\u30d6\u30eb\u306e\u4e0a\u306b\u3042\u308a\u307e\u3059\u3002<\/acronym><\/p>\n<p><em>avoir des pommes\u00a0<span style=\"color: #ff6600\">et<\/span>\u00a0raisins sur la table.<\/em><\/p>\n<p><em>avoir des pommes rouges\u00a0<span style=\"color: #ff6600\">et<\/span>\u00a0raisins verts sur la table.<\/em><\/p>\n<p><acronym title=\"watashi wa nihongo \u00e0 porutogarugo \u00e0 itariago \u00e0 supeingo ga hanaseru.\">\u79c1\u306f\u65e5\u672c\u8a9e\u3068\u30dd\u30eb\u30c8\u30ac\u30eb\u8a9e\u3068\u30a4\u30bf\u30ea\u30a2\u8a9e\u3068\u30b9\u30da\u30a4\u30f3\u8a9e\u304c\u8a71\u305b\u308b\u3002<\/acronym><\/p>\n<p><em>Je parle (peut parler) japonais<span style=\"color: #ff6600\">,<\/span>\u00a0Portugais<span style=\"color: #ff6600\">,<\/span>\u00a0italien\u00a0<span style=\"color: #ff6600\">et<\/span>\u00a0Espagnol.<\/em><\/p>\n<h2>Joindre des phrases japonaises avec la particule pour<\/h2>\n<p>la particule\u00a0<em>je suis<\/em>\u00a0a la capacit\u00e9 de joindre deux phrases ensemble, les transformant en une seule phrase japonaise. A noter que la particule\u00a0<em>je suis<\/em>\u00a0ne peut pas joindre des phrases de p\u00e9riodes diff\u00e9rentes (s\u00e9par\u00e9es par un point) ni appara\u00eetre au d\u00e9but des phrases japonaises.<\/p>\n<p><strong>Exemple:<\/strong><\/p>\n<p><acronym title=\"Watashi ga katta ringo \u00e0 anata ga katta budoo wa teeburu no eu ni arimasu.\"><span style=\"color: #00ff00\">\u79c1\u304c\u8cb7\u3063\u305f\u308a\u3093\u3054<\/span><span style=\"color: #ff6600\">??<\/span><span style=\"color: #3366ff\">\u3042\u306a\u305f\u8cb7\u3063\u305f\u3076\u3069\u3046<\/span>\u306f\u30c6\u30fc\u30d6\u30eb\u306e\u4e0a\u306b\u3042\u308a\u307e\u3059\u3002<\/acronym><\/p>\n<p><em><span style=\"color: #00ff00\">Les pommes que j&#039;ai achet\u00e9es<\/span>\u00a0<span style=\"color: #ff6600\">et<\/span>\u00a0<span style=\"color: #3366ff\">les raisins que tu as achet\u00e9<\/span>\u00a0ils sont sur la table.<\/em><\/p>\n<h2>Contraste et comparaison des mots avec la particule \u00e0<\/h2>\n<p>quand la particule\u00a0<em>je suis<\/em>\u00a0appara\u00eet entre deux noms japonais, il indique un contraste ou une comparaison entre ces deux noms. Dans de tels cas, la particule\u00a0<em>je suis<\/em>\u00a0peut \u00eatre traduit par\u00a0<em>et<\/em>,\u00a0<em>ou<\/em>,\u00a0<em>entre\u00a0<\/em>ou des expressions du genre.<\/p>\n<p><strong>Exemples:<\/strong><\/p>\n<p><acronym title=\"Sukimu miruku \u00e0 futsuu no miruku \u00e0 dochira o kaimashoo ka ?\">\u30b9\u30ad\u30e0\u30df\u30eb\u30af<span style=\"color: #ff6600\">??<\/span>\u666e\u901a\u306e\u30df\u30eb\u30af\u3068\u3069\u3061\u3089\u3092\u8cb7\u3044\u307e\u3057\u3087\u3046\u304b\uff1f<\/acronym><\/p>\n<p><acronym title=\"Sukimu miruku \u00e0 futsuu no miruku \u00e0 dochira o kaimashoo ka ?\"><\/acronym><em>Lequel dois-je acheter, lait \u00e9cr\u00e9m\u00e9\u00a0<span style=\"color: #ff6600\">ou<\/span>\u00a0lait commun?<\/em><\/p>\n<p><acronym title=\"Natsu \u00e0 fuyu \u00e0 de wa kionwa taihen chigaimasu.\">\u590f\u3068\u51ac<span style=\"color: #ff6600\">??<\/span>\u3067\u306f\u6c17\u6e29\u306f\u5927\u5909\u9055\u3044\u307e\u3059\u3002<\/acronym><\/p>\n<p><em><span style=\"color: #ff6600\">Entre<\/span>\u00a0L&#039;\u00e9t\u00e9\u00a0<span style=\"color: #ff6600\">et<\/span>\u00a0hiver, il y a une grande diff\u00e9rence de temp\u00e9rature.<\/em><br \/>\n<br \/>\nNotez que pour conna\u00eetre la signification correcte de la particule\u00a0<em>je suis\u00a0<\/em>Il est n\u00e9cessaire de comprendre le contexte de la phrase. Quand c&#039;est une question, g\u00e9n\u00e9ralement\u00a0<em>je suis<\/em>\u00a0moyens\u00a0<em>ou<\/em>\u00a0ou\u00a0<em>entre<\/em>. Sinon, il y a une forte tendance \u00e0\u00a0<em>je suis<\/em>\u00a0prendre le sens de\u00a0<em>et<\/em>.<\/p>\n<h2>Communion avec la particule japonaise \u00e0<\/h2>\n<p>Dans certaines phrases, lorsque la particule\u00a0<em>je suis<\/em>\u00a0appara\u00eet entre les noms ou les pronoms, il indique la compagnie et peut \u00eatre traduit par\u00a0<em>avec<\/em>.<\/p>\n<p><strong>Exemples:<\/strong><\/p>\n<p><acronym title=\"Kinou wa, otouto \u00e0 kawa et oyogi ni ikimashita.\">\u6628\u65e5\u306f\u3001\u5f1f<span style=\"color: #ff6600\">??<\/span>\u5ddd\u3078\u6cf3\u304e\u306b\u884c\u304d\u307e\u3057\u305f\u3002<\/acronym><\/p>\n<p><em>Hier j&#039;ai nag\u00e9 dans la rivi\u00e8re\u00a0<span style=\"color: #ff6600\">avec<\/span>\u00a0mon fr\u00e8re.<\/em><\/p>\n<p><acronym title=\"Ashita kono mondai ni tsuite, sensei \u00e0 hanasu tsumori desu.\">\u660e\u65e5\u3053\u306e\u554f\u984c\u306b\u3064\u3044\u3066\u3001\u5148\u751f<span style=\"color: #ff6600\">??<\/span>\u8a71\u3059\u3064\u3082\u308a\u3067\u3059\u3002<\/acronym><\/p>\n<p><em>Demain et je discuterai de ce probl\u00e8me\u00a0<span style=\"color: #ff6600\">avec<\/span>\u00a0l&#039;enseignant\/instructeur.<\/em><\/p>\n<h2>Combiner la particule to avec des verbes japonais<\/h2>\n<p>L&#039;une des choses les plus int\u00e9ressantes que j&#039;ai d\u00e9couvertes \u00e0 propos de la particule\u00a0<em>je suis<\/em>, est le fait qu&#039;il peut \u00eatre combin\u00e9 avec\u00a0<a title=\"verbes japonais\" href=\"https:\/\/comoaprenderjapones.net\/fr\/verbes-en-japonais\/\">verbes japonais<\/a>\u00a0pour exprimer les pens\u00e9es et les actions d&#039;autres personnes ou \u00e0 propos de quelque chose.<\/p>\n<p><strong>Exemples:<\/strong><\/p>\n<p><acronym title=\"kinou ga yasumi datta \u00e0 omou\">\u6628\u65e5\u304c\u4f11\u307f\u3060\u3063\u305f<span style=\"color: #ff6600\">\u3068\u601d\u3046<\/span>??<\/acronym><\/p>\n<p><em><span style=\"color: #ff6600\">Je pensais que<\/span>\u00a0hier c&#039;\u00e9tait un jour f\u00e9ri\u00e9.<\/em><\/p>\n<p><acronym title=\"kanojo wa otoko ga shinjimasen toiu.\">\u5f7c\u5973\u306f\u7537\u304c\u4fe1\u3058\u307e\u305b\u3093<span style=\"color: #ff6600\">\u3068\u8a00\u3046<\/span>??<\/acronym><\/p>\n<p><em>Est-ce l\u00e0-bas\u00a0<span style=\"color: #ff6600\">dit que<\/span>\u00a0ne crois pas aux hommes.<\/em><\/p>\n<p>La liste des combinaisons ci-dessous sont les plus couramment trouv\u00e9es dans la langue japonaise\u00a0:<\/p>\n<p><acronym title=\"\u00e0 hanasu\">\u3068\u8a71\u3059<\/acronym>\u00a0(Dis, dis \u00e7a\u2026)<\/p>\n<p><acronym title=\"Je suis parti\">\u3068\u8a00\u3046<\/acronym>\u00a0(Dis \u00e7a...)<\/p>\n<p><acronym title=\"\u00e0 Kangaeru\">\u3068\u8003\u3048\u308b<\/acronym>\u00a0(Pensez que...)<\/p>\n<p><acronym title=\"j&#039;ai aim\u00e9\">\u3068\u601d\u3046<\/acronym>\u00a0(Penser\u2026)<\/p>\n<p><acronym title=\"\u00e0 souzou suru\">\u3068\u5275\u9020\u3059\u308b<\/acronym>\u00a0(Imagine \u00e7a\u2026)<\/p>\n<p><acronym title=\"\u00e0 wakaru\">\u3068\u5206\u304b\u308b<\/acronym>\u00a0(Comprendre que\u2026)<\/p>\n<h2>Conclusion<\/h2>\n<p>Bien qu&#039;il existe d&#039;autres fonctions plus complexes de la particule\u00a0<em>je suis<\/em>, j&#039;ai essay\u00e9 de r\u00e9sumer le plus basique et facile \u00e0 comprendre. Avec cette connaissance, il devient plus facile de comprendre la plupart des phrases japonaises de tous les jours.<\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>En savoir plus sur la particule TO en japonais maintenant\u00a0! La particule japonaise to est une autre particule bien connue des \u00e9tudiants en japonais. Sa fonction la plus courante est simplement de constituer des listes de noms japonais ou m\u00eame de phrases. Contrairement aux autres particules japonaises,<\/p>","protected":false},"author":18,"featured_media":2406,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[74,70],"tags":[71,2,3],"class_list":["post-2403","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-particulas-em-japones","category-gramatica-japonesa","tag-gramatica-japonesa","tag-idioma-japones","tag-nihongo"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/comoaprenderjapones.net\/wp-content\/uploads\/2018\/07\/a-particula-to-em-japones.png?fit=600%2C600&ssl=1","jetpack-related-posts":[{"id":2370,"url":"https:\/\/comoaprenderjapones.net\/fr\/a-particula-ya-em-japones\/","url_meta":{"origin":2403,"position":0},"title":"La particule YA en japonais","author":"L\u00edngua Japonesa","date":"3 de f\u00e9vrier de 2010","format":false,"excerpt":"Agora vamos ampliar seu conhecimento sobre\u00a0a part\u00edcula YA em japon\u00eas! A principal fun\u00e7\u00e3o da part\u00edcula\u00a0ya\u00a0\u00e9 simplesmente criar listas de substantivos japoneses. Dessa forma, podemos citar um conjunto de coisas existentes em algum lugar ou coisas que iremos fazer. Neste momento, muitos leitores devem estar lembrando da part\u00edcula japonesa\u00a0to, que tamb\u00e9m\u2026","rel":"","context":"Dans &quot;Gram\u00e1tica Japonesa&quot;","block_context":{"text":"Gram\u00e1tica Japonesa","link":"https:\/\/comoaprenderjapones.net\/fr\/gramatica-japonesa\/"},"img":{"alt_text":"A part\u00edcula YA em japon\u00eas","src":"https:\/\/i0.wp.com\/comoaprenderjapones.net\/wp-content\/uploads\/2018\/07\/a-particula-ya-em-japones.png?fit=600%2C600&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/comoaprenderjapones.net\/wp-content\/uploads\/2018\/07\/a-particula-ya-em-japones.png?fit=600%2C600&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/comoaprenderjapones.net\/wp-content\/uploads\/2018\/07\/a-particula-ya-em-japones.png?fit=600%2C600&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":1661,"url":"https:\/\/comoaprenderjapones.net\/fr\/sujeito-das-frases-em-japones\/","url_meta":{"origin":2403,"position":1},"title":"Le sujet des phrases japonaises","author":"L\u00edngua Japonesa","date":"3 de novembre de 2009","format":false,"excerpt":"Aprenda mais sobre\u00a0o sujeito das frases em japon\u00eas no nihongo! Como j\u00e1 estudamos\u00a0a ordem das palavras nas frases em japon\u00eas, sabemos que elas possuem uma organiza\u00e7\u00e3o inversa das palavras na l\u00edngua portuguesa. Nas frases em japon\u00eas, geralmente a ordem das palavras \u00e9\u00a0sujeito\u00a0+\u00a0objeto\u00a0(predicado ou resto da frase) +\u00a0verbo. Para ficar mais\u2026","rel":"","context":"Dans &quot;Curso de Japon\u00eas Gr\u00e1tis&quot;","block_context":{"text":"Curso de Japon\u00eas Gr\u00e1tis","link":"https:\/\/comoaprenderjapones.net\/fr\/curso-de-japones-gratis\/"},"img":{"alt_text":"O sujeito das frases em japon\u00eas - part\u00edcula WA ","src":"https:\/\/i0.wp.com\/comoaprenderjapones.net\/wp-content\/uploads\/2015\/03\/ha-150x150.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":2820,"url":"https:\/\/comoaprenderjapones.net\/fr\/particula-mo-em-japones\/","url_meta":{"origin":2403,"position":2},"title":"La particule MO en japonais","author":"L\u00edngua Japonesa","date":"6 de janvier de 2010","format":false,"excerpt":"Em japon\u00eas, a fun\u00e7\u00e3o mais comum da part\u00edcula\u00a0mo\u00a0\u00e9 indicar uma esp\u00e9cie de similaridade entre palavras da mesma senten\u00e7a. Segundo a\u00a0gram\u00e1tica japonesa, a part\u00edcula\u00a0mo\u00a0pode substituir outras part\u00edculas em frases paralelas, colocando duas palavras em p\u00e9 de igualdade ou assumindo o mesmo significado de palavras como\u00a0tamb\u00e9m,\u00a0bem como,\u00a0t\u00e3o...quanto\u00a0e outras com o mesmo significado.\u2026","rel":"","context":"Dans &quot;Gram\u00e1tica Japonesa&quot;","block_context":{"text":"Gram\u00e1tica Japonesa","link":"https:\/\/comoaprenderjapones.net\/fr\/gramatica-japonesa\/"},"img":{"alt_text":"A part\u00edcula mo - \u3082","src":"https:\/\/i0.wp.com\/comoaprenderjapones.net\/wp-content\/uploads\/2010\/01\/particula-MO-em-japones.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/comoaprenderjapones.net\/wp-content\/uploads\/2010\/01\/particula-MO-em-japones.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/comoaprenderjapones.net\/wp-content\/uploads\/2010\/01\/particula-MO-em-japones.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/comoaprenderjapones.net\/wp-content\/uploads\/2010\/01\/particula-MO-em-japones.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/comoaprenderjapones.net\/wp-content\/uploads\/2010\/01\/particula-MO-em-japones.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":1637,"url":"https:\/\/comoaprenderjapones.net\/fr\/gramatica-japonesa-fundamental\/","url_meta":{"origin":2403,"position":3},"title":"grammaire japonaise fondamentale","author":"L\u00edngua Japonesa","date":"7 de novembre de 2009","format":false,"excerpt":"Aprenda mais sobre a\u00a0gram\u00e1tica japonesa fundamental para voc\u00ea estudante de nihongo! No artigo de hoje, vamos entender alguns dos fundamentos da l\u00edngua japonesa, compreendendo a forma\u00e7\u00e3o de frases simples. Gram\u00e1tica japonesa fundamental O conte\u00fado de hoje tamb\u00e9m ajudar\u00e1 a entender melhor tudo o que j\u00e1 aprendemos nos artigos anteriores. Apesar\u2026","rel":"","context":"Dans &quot;Curso de Japon\u00eas Gr\u00e1tis&quot;","block_context":{"text":"Curso de Japon\u00eas Gr\u00e1tis","link":"https:\/\/comoaprenderjapones.net\/fr\/curso-de-japones-gratis\/"},"img":{"alt_text":"estudando japones","src":"https:\/\/i0.wp.com\/comoaprenderjapones.net\/wp-content\/uploads\/2014\/09\/estudando_japones.jpg?fit=450%2C300&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1729,"url":"https:\/\/comoaprenderjapones.net\/fr\/particulas-basicas-em-japones\/","url_meta":{"origin":2403,"position":4},"title":"Particules de base en japonais","author":"L\u00edngua Japonesa","date":"15 de novembre de 2009","format":false,"excerpt":"Conhe\u00e7a e aprenda mais sobre\u00a0as part\u00edculas b\u00e1sicas em japon\u00eas! As part\u00edculas s\u00e3o pequenos elementos gramaticais, geralmente escritas usando uma \u00fanica s\u00edlaba do\u00a0alfabeto japon\u00eas em hiragana, e n\u00e3o possuem uma tradu\u00e7\u00e3o espec\u00edfica. A fun\u00e7\u00e3o das part\u00edculas em japon\u00eas \u00e9 puramente gramatical, servindo como uma marca para identificar a fun\u00e7\u00e3o das palavras\u2026","rel":"","context":"Dans &quot;Curso de Japon\u00eas Gr\u00e1tis&quot;","block_context":{"text":"Curso de Japon\u00eas Gr\u00e1tis","link":"https:\/\/comoaprenderjapones.net\/fr\/curso-de-japones-gratis\/"},"img":{"alt_text":"As part\u00edculas b\u00e1sicas em japon\u00eas - \u5f7c\u306f\u65e5\u672c\u4eba\u3067\u3059\u3002","src":"https:\/\/i0.wp.com\/comoaprenderjapones.net\/wp-content\/uploads\/2009\/11\/particulas-basicas-em-japones.png?fit=500%2C400&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1735,"url":"https:\/\/comoaprenderjapones.net\/fr\/particulas-para-final-de-frases-em-japones\/","url_meta":{"origin":2403,"position":5},"title":"Particules pour la fin des phrases en japonais","author":"L\u00edngua Japonesa","date":"3 de novembre de 2009","format":false,"excerpt":"Saiba mais sobre as\u00a0Part\u00edculas para o final de frases em japon\u00eas! Eu estava estudando a finaliza\u00e7\u00e3o de frases em japon\u00eas usando part\u00edculas e descobri algumas part\u00edculas b\u00e1sicas e bem interessantes. Part\u00edculas para o final de frases em japon\u00eas Apesar de possu\u00edrem significados semelhantes, essas part\u00edculas japonesas possuem caracter\u00edsticas bem particulares.\u2026","rel":"","context":"Dans &quot;Curso de Japon\u00eas Gr\u00e1tis&quot;","block_context":{"text":"Curso de Japon\u00eas Gr\u00e1tis","link":"https:\/\/comoaprenderjapones.net\/fr\/curso-de-japones-gratis\/"},"img":{"alt_text":"Part\u00edculas para o final de frases em japon\u00eas","src":"https:\/\/i0.wp.com\/comoaprenderjapones.net\/wp-content\/uploads\/2018\/03\/particulas-para-final-de-frases-em-japones.png?fit=500%2C400&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/comoaprenderjapones.net\/fr\/wp-json\/wp\/v2\/posts\/2403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comoaprenderjapones.net\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comoaprenderjapones.net\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comoaprenderjapones.net\/fr\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/comoaprenderjapones.net\/fr\/wp-json\/wp\/v2\/comments?post=2403"}],"version-history":[{"count":0,"href":"https:\/\/comoaprenderjapones.net\/fr\/wp-json\/wp\/v2\/posts\/2403\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comoaprenderjapones.net\/fr\/wp-json\/wp\/v2\/media\/2406"}],"wp:attachment":[{"href":"https:\/\/comoaprenderjapones.net\/fr\/wp-json\/wp\/v2\/media?parent=2403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comoaprenderjapones.net\/fr\/wp-json\/wp\/v2\/categories?post=2403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comoaprenderjapones.net\/fr\/wp-json\/wp\/v2\/tags?post=2403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}