{"id":1642,"date":"2009-11-03T04:26:27","date_gmt":"2009-11-03T06:26:27","guid":{"rendered":"https:\/\/comoaprenderjapones.net\/?p=1642"},"modified":"2021-03-26T15:06:17","modified_gmt":"2021-03-26T18:06:17","slug":"como-fazer-perguntas-em-japones","status":"publish","type":"post","link":"https:\/\/comoaprenderjapones.net\/hi\/como-fazer-perguntas-em-japones\/","title":{"rendered":"Como fazer perguntas em japon\u00eas"},"content":{"rendered":"<div class=\"04dd1bbe232ab3e807c32e49b7a4a9d3\" data-index=\"2\" style=\"float: none; margin:0px;\">\n<script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-0652292147574552\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<!-- Ads responsivo Inicio Post CAJap -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-0652292147574552\"\r\n     data-ad-slot=\"3298668993\"\r\n     data-ad-format=\"auto\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img decoding=\"async\" width=\"100\" height=\"78\" src=\"https:\/\/comoaprenderjapones.net\/wp-content\/uploads\/2018\/03\/fazer-perguntas-em-japones.jpg\" alt=\"Como fazer perguntas em japon\u00eas\" class=\"wp-image-1643\" title=\"Como fazer perguntas em japon\u00eas\"\/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Saiba agora <strong>como fazer perguntas em japon\u00eas<\/strong>!<\/em><br \/><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fazer perguntas em japon\u00eas \u00e9 algo t\u00e3o simples quanto fazer perguntas em portugu\u00eas. Nos artigos anteriores, sobre&nbsp;<a title=\"Gram\u00e1tica japonesa fundamental\" href=\"https:\/\/comoaprenderjapones.net\/hi\/gramatica-japonesa-fundamental\/\">a gram\u00e1tica japonesa fundamental<\/a>, falei um pouco sobre como usar a part\u00edcula&nbsp;<acronym title=\"ka\">\u304b<\/acronym>para fazer perguntas em japon\u00eas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Como fazer perguntas em japon\u00eas<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Por causa disso, achei que seria interessante escrever novamente sobre o assunto, mostrando como fazer perguntas em japon\u00eas de modo mais abrangente e sobre uma nova perspectiva, ampliando os horizontes de palavras para quem j\u00e1 sabe um pouco sobre este assunto.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Nani, itsu, doko e dare \u2013 O que, quando, onde e quem<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Vamos come\u00e7ar pelo uso de&nbsp;<acronym title=\"nani ou nan | o que\">\u4f55<\/acronym>, que pode ser usado para fazer perguntas em japon\u00eas, sobre todo o tipo de coisa e assunto desejado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para fazer perguntas em japon\u00eas usando&nbsp;<acronym title=\"nani ou nan | o que\">\u4f55<\/acronym>, basta substituir o objeto direto da frase por&nbsp;<acronym title=\"nani ou nan | o que\">\u4f55<\/acronym>&nbsp;e adicionar a part\u00edcula&nbsp;<acronym title=\"ka\">\u304b<\/acronym>&nbsp;no final da frase.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Exemplos:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><acronym title=\"nan desu ka? | o que \u00e9?\">\u4f55\u3067\u3059\u304b\u3002<\/acronym><br \/>Nan desu ka? ( o que \u00e9?)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><acronym title=\"kore wa nan desu ka? | O que \u00e9 isto?\">\u3053\u308c\u306f\u4f55\u3067\u3059\u304b\uff1f<\/acronym><br \/>Kore wa nan desu ka? (O que \u00e9 isto?)<br \/><acronym title=\"kore wa kame ga iru. | Isto \u00e9 uma tartaruga.\">\u3053\u308c\u306f\u4e80\u304c\u3044\u308b\u3002<\/acronym><br \/>Kore wa kame ga iru. (Isto \u00e9 uma tartaruga.)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><acronym title=\"nani ga tabetai no? | O que deseja comer?\">\u4f55\u304c\u98df\u3079\u305f\u3044\u306e\uff1f<\/acronym><br \/>Nani ga tabetai no? (O que deseja comer?)<br \/><acronym title=\"sushi ga tabetai. | Comer sushi.\">\u3059\u3057\u304c\u98df\u3079\u305f\u3044\u3002<\/acronym><br \/>sushi ga tabetai. (Comer sushi.)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><acronym title=\"sore wa nan desu ka? | O que \u00e9 isso?\">\u305d\u308c\u306f\u4f55\u3067\u3059\u304b\uff1f<\/acronym><br \/>Sore wa nan desu ka? (O que \u00e9 isso?)<br \/><acronym title=\"sore wa chiizu desu. | Isso \u00e9 queijo.\">\u305d\u308c\u306f\u30c1\u30fc\u30ba\u3067\u3059\u3002<\/acronym><br \/>Sore wa chiizu desu.  (Isso \u00e9 queijo.)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Percebam que a pron\u00fancia de&nbsp;<acronym title=\"nani ou nan | o que\">\u4f55<\/acronym>&nbsp;muda de acordo com a posi\u00e7\u00e3o dela na frase. Para saber mais sobre como pronunciar&nbsp;<acronym title=\"nani ou nan | o que\">\u4f55<\/acronym>&nbsp;corretamente, sugiro que leia o artigo \u201c<a href=\"https:\/\/comoaprenderjapones.net\/hi\/quando-usar-nan-ou-nani\/\">Quando usar nan ou nani em japon\u00eas<\/a>\u201c.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seguindo adiante,&nbsp;<acronym title=\"itsu | quanto\">\u3044\u3064<\/acronym>,&nbsp;<acronym title=\"dare | quem\">\u8ab0<\/acronym>&nbsp;e&nbsp;<acronym title=\"doko | onde\">\u3069\u3053<\/acronym>&nbsp;s\u00e3o usados da mesma forma que&nbsp;<acronym title=\"nani ou nan | o que\">\u4f55<\/acronym>. Assim, basta apens substituir o objeto das frases por qualquer uma das palavras citadas acima.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Exemplos:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><acronym title=\"itsu burajiru e itta ka? | Quando voc\u00ea foi ao brasil?\">\u3044\u3064\u30d6\u30e9\u30b8\u30eb\u3078\u884c\u3063\u305f\u304b\uff1f<\/acronym><br \/>Itsu burajiru e itta ka?  (Quando voc\u00ea foi ao brasil?)<br \/><acronym title=\"kyonen, burajiru e itta. | Ano passado, eu fui Brasil.\">\u53bb\u5e74\u3001\u30d6\u30e9\u30b8\u30eb\u3078\u884c\u3063\u305f\u3002<\/acronym><br \/>Kyonen, burajiru e itta.  (Ano passado, eu fui Brasil.)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><acronym title=\"watashi no hon ga doko ni arimasu ka? | Onde est\u00e1 meu livro?\">\u79c1\u306e\u672c\u304c\u3069\u3053\u306b\u3042\u308a\u307e\u3059\u304b\uff1f<\/acronym><br \/>Watashi no hon ga doko ni arimasu ka?  (Onde est\u00e1 meu livro?)<br \/><acronym title=\"anata no hon ga teeburu no ue ni arimasu. | Seu livro est\u00e1 em cima da mesa.\">\u3042\u306a\u305f\u306e\u672c\u304c\u30c6\u30fc\u30d6\u30eb\u306e\u4e0a\u306b\u3042\u308a\u307e\u3059\u3002<\/acronym><br \/>Anata no hon ga teeburu no ue ni arimasu.  (Seu livro est\u00e1 em cima da mesa.)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><acronym title=\"dare ga biiru wo nondano? | Quem bebeu minha cerveja?\">\u8ab0\u304c\u30d3\u30fc\u30eb\u3092\u98f2\u3093\u3060\u306e\uff1f<\/acronym><br \/>dare ga biiru wo nondano?  (Quem bebeu minha cerveja?)<br \/><acronym title=\"Honda-san ga biiru wo nonda. | O senhor Honda bebeu a cerveja.\">\u672c\u7530\u3055\u3093\u304c\u30d3\u30fc\u30eb\u3092\u98f2\u3093\u3060\u3002<\/acronym><br \/><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><acronym title=\"dare ga biiru wo nondano? | Quem bebeu minha cerveja?\">\u8ab0\u304c\u30d3\u30fc\u30eb\u3092\u98f2\u3093\u3060\u306e\uff1f<\/acronym><br \/>dare ga biiru wo nondano?  (Quem bebeu minha cerveja?)<br \/><acronym title=\"Honda-san ga biiru wo nonda. | O senhor Honda bebeu a cerveja.\">\u672c\u7530\u3055\u3093\u304c\u30d3\u30fc\u30eb\u3092\u98f2\u3093\u3060\u3002<\/acronym><br \/><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><acronym title=\"dare ga biiru wo nondano? | Quem bebeu minha cerveja?\">\u8ab0\u304c\u30d3\u30fc\u30eb\u3092\u98f2\u3093\u3060\u306e\uff1f<\/acronym><br \/>dare ga biiru wo nondano?  (Quem bebeu minha cerveja?)<br \/><acronym title=\"Honda-san ga biiru wo nonda. | O senhor Honda bebeu a cerveja.\">\u672c\u7530\u3055\u3093\u304c\u30d3\u30fc\u30eb\u3092\u98f2\u3093\u3060\u3002<\/acronym><br \/>Honda-san ga biiru wo nonda.  (O senhor Honda bebeu a cerveja.)<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Ikura e dorekurai &#8211; Quanto em japon\u00eas<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Pelo que eu soube, existem muitas varia\u00e7\u00f5es de express\u00f5es para fazer perguntas em japon\u00eas usando \u201cquanto custa\u201d e \u201cquanto falta\u201d. As duas express\u00f5es mais b\u00e1sica s\u00e3o&nbsp;<acronym title=\"ikura | quanto custa.\">\u3044\u304f\u3089<\/acronym>&nbsp;e&nbsp;<acronym title=\"dorekurai | quanto falta\">\u3069\u308c\u304f\u3089\u3044<\/acronym>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Geralmente&nbsp;<acronym title=\"ikura | quanto custa.\">\u3044\u304f\u3089<\/acronym>&nbsp;est\u00e1 relacionada a quantidade de dinheiro, enquanto&nbsp;<acronym title=\"dorekurai | quanto falta\">\u3069\u308c\u304f\u3089\u3044<\/acronym>&nbsp;est\u00e1 relacionado a dist\u00e2ncias, larguras, dimens\u00f5es e etc.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Exemplos:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><acronym title=\"kono hon wa ikura desu ka? | Quanto custa este livro?\">\u3053\u306e\u672c\u306f\u3044\u304f\u3089\u3067\u3059\u304b\u3002<\/acronym><br \/>kono hon wa ikura desu ka?  (Quanto custa este livro?)<br \/><acronym title=\"kono hon wa nihyaku en desu. | Este livro custa duzentos yens.\">\u3053\u306e\u672c\u306f\uff12\uff10\uff10\u5186\u3067\u3059\u3002<\/acronym><br \/>kono hon wa nihyaku en desu.  (Este livro custa duzentos yens.)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><acronym title=\"Toukyu wa dorekurai desu ka? Quanto falta at\u00e9 T\u00f3kyo?\">\u6771\u4eac\u306f\u3069\u308c\u304f\u3089\u3044\u3067\u3059\u304b\u3002<\/acronym><br \/>Toukyu wa dorekurai desu ka? (Quanto falta at\u00e9 T\u00f3quio?)<br \/><acronym title=\"nan kiro motooi desu. | Alguns kil\u00f4metros.\">\u4f55\u30ad\u30ed\u3082\u9060\u3044\u3067\u3059\u3002<\/acronym><br \/>nan kiro motooi desu.  (Alguns quil\u00f4metros.)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Outro caminho para fazer perguntas em japon\u00eas, relacionadas com quantidades, \u00e9 usar os contadores. Eu j\u00e1 escrevi sobre alguns deles em artigos anteriores. Se desejar revisar ou conhecer os contadores, sugiro ler o artigo \u201c<a href=\"https:\/\/comoaprenderjapones.net\/hi\/contadores-para-contar-em-japones\/\">Contadores para contar em japon\u00eas<\/a>\u201c.<br \/><br \/><strong>Exemplos:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><acronym title=\"hon wo nansatsu kaimasu ka? | Quantos livros vai comprar?\">\u672c\u3092\u4f55\u518a\u8cb7\u3044\u307e\u3059\u304b\uff1f<\/acronym><br \/>Hon wo nansatsu kaimasu ka?  (Quantos livros vai comprar?)<br \/><acronym title=\"yonsatsu desu. | Quatro livros.\">\u56db\u518a\u3067\u3059\u3002<\/acronym><br \/>Yonsatsu desu.  (Quatro livros.)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><acronym title=\"conpyuuta o nandai motte iru? | Quantos computadores voc\u00ea tem?\">\u30b3\u30f3\u30d4\u30e5\u30fc\u30bf\u3092\u4f55\u53f0\u6301\u3063\u3066\u3044\u308b\uff1f<\/acronym><br \/>Conpyuuta o nandai motte iru? (Quantos computadores voc\u00ea tem?)<br \/><acronym title=\"sandai desu | Tr\u00eas.\">\u4e09\u53f0\u3067\u3059\u3002<\/acronym><br \/>Sandai desu  (Tr\u00eas.)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Uma coisa interessante \u00e9 que, quando n\u00e3o sabemos o contador correto para algo, podemos usar&nbsp;<a href=\"https:\/\/comoaprenderjapones.net\/hi\/contadores-para-contar-em-japones\/\">o contador generalista em japon\u00eas<\/a>. Neste caso,&nbsp;<acronym title=\"ikura | quanto custa.\">\u3044\u304f\u3089<\/acronym>&nbsp;vira&nbsp;<acronym title=\"ikutsu | quanto.\">\u3044\u304f\u3064<\/acronym>, recebendo a extens\u00e3o do contador generalista e possibilitando fazer perguntas em japon\u00eas para v\u00e1rias coisas diferentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Exemplo:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><acronym title=\"kaki o ikutsu tabemasuka? | Quantos caquis vai comer?\">\u67ff\u3092\u3044\u304f\u3064\u98df\u3079\u307e\u3059\u304b\uff1f<\/acronym><br \/>kaki o ikutsu tabemasuka? (Quantos caquis vai comer?)<br \/><acronym title=\"mitsu desu | tr\u00eas.\">\u4e09\u3064\u3067\u3059\u3002<\/acronym><br \/>mitsu desu  (tr\u00eas.)<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Doushite \u2013 porque em japon\u00eas<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Para saber a raz\u00e3o de alguma coisa em japon\u00eas, usamos a palavra&nbsp;<acronym title=\"doushite | por que\">\u3069\u3046\u3057\u3066<\/acronym>. O caminho mais comum para responder perguntas em japon\u00eas feitas com&nbsp;<acronym title=\"doushite | porque\">\u3069\u3046\u3057\u3066<\/acronym>&nbsp;\u00e9 adicionando&nbsp;<acronym title=\"kara | porque\">\u304b\u3089<\/acronym>&nbsp;no final da resposta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Assim, para responder uma pergunta feita com&nbsp;<acronym title=\"doushite | por que\">\u3069\u3046\u3057\u3066<\/acronym>, basta criar a frase para resposta e adicionar&nbsp;<acronym title=\"kara | porque\">\u304b\u3089<\/acronym>&nbsp;no final dela.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Exemplo:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><acronym title=\"doushite nihon ni ikimasu ka? | Por que voc\u00ea vai para o Jap\u00e3o?\">\u3069\u3046\u3057\u3066\u65e5\u672c\u306b\u884c\u304d\u307e\u3059\u304b\uff1f<\/acronym><br \/>Doushite nihon ni ikimasu ka?  (Por que voc\u00ea vai para o Jap\u00e3o?)<br \/><acronym title=\"nihon o benkyoushitai kara. | Porque eu quero aprender japon\u00eas.\">\u65e5\u672c\u8a9e\u3092\u52c9\u5f37\u3057\u305f\u3044\u304b\u3089\u3002<\/acronym><br \/>Nihon o benkyoushitai kara.  (Porque eu quero aprender japon\u00eas.)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><small>Os cr\u00e9ditos da imagem pertencem \u00e0&nbsp;<a href=\"https:\/\/www.flickr.com\/photos\/oberazzi\/\" target=\"_blank\" rel=\"nofollow noopener\">oberazzi<\/a>.<\/small><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Exerc\u00edcio de caligrafia de kanjis<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Abaixo seguem os&nbsp;<a href=\"https:\/\/comoaprenderjapones.net\/hi\/os-simbolos-japoneses-do-jouyou-kanji\/\">s\u00edmbolos japoneses ideogr\u00e1ficos<\/a>&nbsp;usados neste artigo. Selecionando os kanjis desejados e copie-os e cole na&nbsp;<a href=\"https:\/\/comoaprenderjapones.net\/hi\/in\/imprimir-para-treinar-kanas-e-kanjis\/\" target=\"_blank\" rel=\"noopener\">Planilha para pr\u00e1tica de Kana e Kanji<\/a>&nbsp; clicando no&nbsp;bot\u00e3o Gerar, ser\u00e1 aberta uma nova janela onde voc\u00ea vai poder ver o arquivo para impress\u00e3o. Depois basta imprimir os s\u00edmbolos e tentar escrever sozinho. \u00c9 s\u00f3 imprimir e praticar!<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td>\u4f55<\/td><td>\u4e80<\/td><td>\u98df<\/td><td>\u884c<\/td><td>\u53bb<\/td><\/tr><tr><td>\u5e74<\/td><td>\u672c<\/td><td>\u4e0a<\/td><td>\u8ab0<\/td><td>\u98f2<\/td><\/tr><tr><td>\u7530<\/td><td>\u5186<\/td><td>\u6771<\/td><td>\u4eac<\/td><td>\u518a<\/td><\/tr><tr><td>\u8cb7<\/td><td>\u53f0<\/td><td>\u6301<\/td><td>\u67ff<\/td><td>\u65e5<\/td><\/tr><tr><td>\u8a9e<\/td><td>\u52c9<\/td><td>\u5f37<\/td><\/tr><\/tbody><\/table><\/figure>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Saiba agora como fazer perguntas em japon\u00eas! Fazer perguntas em japon\u00eas \u00e9 algo t\u00e3o simples quanto fazer perguntas em portugu\u00eas. Nos artigos anteriores, sobre&nbsp;a gram\u00e1tica japonesa fundamental, falei um pouco sobre como usar a part\u00edcula&nbsp;\u304bpara<\/p>","protected":false},"author":18,"featured_media":1645,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[49,70,60],"tags":[27,71,2,3],"class_list":["post-1642","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curso-de-japones-gratis","category-gramatica-japonesa","category-vocabulario-japones","tag-gramatica","tag-gramatica-japonesa","tag-idioma-japones","tag-nihongo","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/comoaprenderjapones.net\/hi\/wp-json\/wp\/v2\/posts\/1642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comoaprenderjapones.net\/hi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comoaprenderjapones.net\/hi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comoaprenderjapones.net\/hi\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/comoaprenderjapones.net\/hi\/wp-json\/wp\/v2\/comments?post=1642"}],"version-history":[{"count":0,"href":"https:\/\/comoaprenderjapones.net\/hi\/wp-json\/wp\/v2\/posts\/1642\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comoaprenderjapones.net\/hi\/wp-json\/wp\/v2\/media\/1645"}],"wp:attachment":[{"href":"https:\/\/comoaprenderjapones.net\/hi\/wp-json\/wp\/v2\/media?parent=1642"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comoaprenderjapones.net\/hi\/wp-json\/wp\/v2\/categories?post=1642"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comoaprenderjapones.net\/hi\/wp-json\/wp\/v2\/tags?post=1642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}