{"id":1182,"date":"2009-11-01T17:51:25","date_gmt":"2009-11-01T19:51:25","guid":{"rendered":"https:\/\/comoaprenderjapones.net\/?p=1182"},"modified":"2018-02-25T16:35:22","modified_gmt":"2018-02-25T19:35:22","slug":"familia-do-t-em-hiragana","status":"publish","type":"post","link":"https:\/\/comoaprenderjapones.net\/nb\/familia-do-t-em-hiragana\/","title":{"rendered":"T-familien i hiragana"},"content":{"rendered":"<div class=\"527a9b96e85f09e5ab5a4598fe8592a3\" data-index=\"2\" style=\"float: none; margin:0px;\">\n<script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-0652292147574552\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<!-- Ads responsivo Inicio Post CAJap -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-0652292147574552\"\r\n     data-ad-slot=\"3298668993\"\r\n     data-ad-format=\"auto\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p><em>Conhe\u00e7a\u00a0a <strong>fam\u00edlia do T em hiragana<\/strong> og l\u00e6r hvordan du skriver strekene dine riktig!<\/em><\/p>\n<h2>T-familien i hiragana<\/h2>\n<p>\u305f = TA<\/p>\n<p>Na s\u00edlaba TA , encontramos dois s\u00edmbolos bem conhecidos: uma espada e uma copiadora. Quando uma espada \u00e9 usada numa copiadora, a espada \u00e9 clonada em v\u00e1rias outras que, ao sa\u00edrem da m\u00e1quina de copiar, produzem o barulho de uma metralhadora. TA!TA!TA!TA!..<\/p>\n<p class=\"align-center\"><img decoding=\"async\" class=\"aligncenter wp-image-1185 size-full\" title=\"Ordem dos tra\u00e7os do hiragana TA\" src=\"https:\/\/comoaprenderjapones.net\/wp-content\/uploads\/2009\/11\/hiragana-ta-ordem-dos-tracos.jpg\" alt=\"Ordem dos tra\u00e7os do hiragana TA\" width=\"320\" height=\"63\" srcset=\"https:\/\/comoaprenderjapones.net\/wp-content\/uploads\/2009\/11\/hiragana-ta-ordem-dos-tracos.jpg 320w, https:\/\/comoaprenderjapones.net\/wp-content\/uploads\/2009\/11\/hiragana-ta-ordem-dos-tracos-300x59.jpg 300w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/><\/p>\n<p>\u3061 = TCHI<br \/>\nAqui encontramos uma tsuname ( onda gigante ) composta de espadas e n\u00e3o de \u00e1gua. Veja que a espada est\u00e1 em cima de uma onda.<\/p>\n<p class=\"align-center\"><img decoding=\"async\" class=\"aligncenter wp-image-1186 size-full\" title=\"Ordem dos tra\u00e7os do hiragana CHI\" src=\"https:\/\/comoaprenderjapones.net\/wp-content\/uploads\/2009\/11\/hiragana-chi-ordem-dos-tracos.jpg\" alt=\"Ordem dos tra\u00e7os do hiragana CHI\" width=\"182\" height=\"69\" \/><\/p>\n<p>\u3064 = TSU<br \/>\nA s\u00edlaba TSU ficou f\u00e1cil. Uma onda gigante que destr\u00f3i todas as cidades localizadas no litoral.<\/p>\n<p class=\"align-center\"><img decoding=\"async\" class=\"aligncenter wp-image-1187 size-full\" title=\"Ordem dos tra\u00e7os do hiragana TSU\" src=\"https:\/\/comoaprenderjapones.net\/wp-content\/uploads\/2009\/11\/hiragana-tsu-ordem-dos-tracos.jpg\" alt=\"Ordem dos tra\u00e7os do hiragana TSU\" width=\"97\" height=\"69\" \/><\/p>\n<p><br \/>\n\u3066 = TE<br \/>\nA s\u00edlaba TE nada mais \u00e9 do que um \u201cT\u201d com o tra\u00e7o torto. F\u00e1cil f\u00e1cil!<\/p>\n<p class=\"align-center\"><img decoding=\"async\" class=\"aligncenter wp-image-1188 size-full\" title=\"Ordem dos tra\u00e7os do hiragana TE\" src=\"https:\/\/comoaprenderjapones.net\/wp-content\/uploads\/2009\/11\/hiragana-te-ordem-dos-tracos.jpg\" alt=\"Ordem dos tra\u00e7os do hiragana TE\" width=\"97\" height=\"69\" \/><\/p>\n<p>\u3068= TO<br \/>\nPerceba que o s\u00edmbolo \u3068parece o nosso Y. S\u00f3 que a perna do TO foi entortada por um palito.<\/p>\n<p class=\"align-center\"><img decoding=\"async\" class=\"aligncenter wp-image-1189 size-full\" title=\"Ordem dos tra\u00e7os do hiragana TO\" src=\"https:\/\/comoaprenderjapones.net\/wp-content\/uploads\/2009\/11\/hiragana-to-ordem-dos-tracos.jpg\" alt=\"Ordem dos tra\u00e7os do hiragana TO\" width=\"161\" height=\"69\" \/><\/p>\n<h2>Den japanske kalligrafi\u00f8velsen<\/h2>\n<p>Velg den\u00a0<a href=\"https:\/\/comoaprenderjapones.net\/nb\/komplett-hiragana-tabell\/\">symbolene i det japanske alfabetet<\/a>\u00a0og klikk p\u00e5 knappen Generer i\u00a0<a href=\"https:\/\/comoaprenderjapones.net\/nb\/in\/imprimir-para-treinar-kanas-e-kanjis\/\" target=\"_blank\" rel=\"noopener\">\u00d8veark for kana og kanji<\/a>\u00a0. Da \u00e5pnes et nytt vindu med den utskrivbare filen. Alt du trenger \u00e5 gj\u00f8re er \u00e5 skrive den ut, dekke til de gr\u00e5 hiragana-symbolene og s\u00e5 pr\u00f8ve \u00e5 skrive den selv. Bare skriv ut og \u00f8v deg!<\/p>\n<table style=\"height: 35px\" border=\"0\" width=\"414\" cellspacing=\"2\" cellpadding=\"2\">\n<tbody>\n<tr>\n<td align=\"left\" valign=\"middle\"><label>\u00a0\u305f<\/label><\/td>\n<td align=\"left\" valign=\"middle\"><label>\u00a0\u3061<\/label><\/td>\n<td align=\"left\" valign=\"middle\"><label>\u00a0\u3064<\/label><\/td>\n<td align=\"left\" valign=\"middle\"><label>\u00a0\u3066<\/label><\/td>\n<td align=\"left\" valign=\"middle\"><label>\u00a0\u3068<\/label><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Conhe\u00e7a\u00a0a fam\u00edlia do T em hiragana e saiba como escrever corretamente seus tra\u00e7os! A fam\u00edlia do T em hiragana \u305f = TA Na s\u00edlaba TA , encontramos dois s\u00edmbolos bem conhecidos: uma espada e uma<\/p>","protected":false},"author":18,"featured_media":1193,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46,47],"tags":[16,54],"class_list":["post-1182","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alfabeto-japones","category-alfabeto-japones-hiragana","tag-alfabeto-japones","tag-hiragana","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/comoaprenderjapones.net\/nb\/wp-json\/wp\/v2\/posts\/1182","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comoaprenderjapones.net\/nb\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comoaprenderjapones.net\/nb\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comoaprenderjapones.net\/nb\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/comoaprenderjapones.net\/nb\/wp-json\/wp\/v2\/comments?post=1182"}],"version-history":[{"count":0,"href":"https:\/\/comoaprenderjapones.net\/nb\/wp-json\/wp\/v2\/posts\/1182\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comoaprenderjapones.net\/nb\/wp-json\/wp\/v2\/media\/1193"}],"wp:attachment":[{"href":"https:\/\/comoaprenderjapones.net\/nb\/wp-json\/wp\/v2\/media?parent=1182"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comoaprenderjapones.net\/nb\/wp-json\/wp\/v2\/categories?post=1182"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comoaprenderjapones.net\/nb\/wp-json\/wp\/v2\/tags?post=1182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}