{"id":1451,"date":"2009-11-05T07:12:17","date_gmt":"2009-11-05T09:12:17","guid":{"rendered":"https:\/\/comoaprenderjapones.net\/?p=1451"},"modified":"2018-03-04T17:49:58","modified_gmt":"2018-03-04T20:49:58","slug":"como-usar-as-letras-japonesas-no-computador","status":"publish","type":"post","link":"https:\/\/comoaprenderjapones.net\/vi\/como-usar-as-letras-japonesas-no-computador\/","title":{"rendered":"Como usar as letras japonesas no computador"},"content":{"rendered":"<div class=\"3f06cfaed421c312d090106fe7464974\" data-index=\"2\" style=\"float: none; margin:0px;\">\n<script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-0652292147574552\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<!-- Ads responsivo Inicio Post CAJap -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-0652292147574552\"\r\n     data-ad-slot=\"3298668993\"\r\n     data-ad-format=\"auto\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p>N\u00e3o sei quantos de voc\u00eas s\u00e3o usu\u00e1rios iniciantes no ramo de tecnologia e computadores, mas como tenho recebido alguns e-mails perguntando como ver as letras japonesas no computador e como instalar estes tipos de arquivos. Ent\u00e3o resolvi escrever sobre o assunto, criando um guia com informa\u00e7\u00f5es gerais sobre como instalar, remover e utilizar as letras japonesas no computador.<\/p>\n<h2>Como usar as letras japonesas no computador<\/h2>\n<p>Com esta p\u00e1gina, espero poder ajudar os leitores do L\u00edngua Japonesa \u00e0 lidar melhor com as letras japonesas, facilitando sua utiliza\u00e7\u00e3o no computador e permitindo o uso de mais de uma fonte. Assim voc\u00ea pode variar os estilos de letras japonesas que voc\u00ea usa em seu computador e come\u00e7ar a usar as que mais gosta, sem efeitos colaterais e perda de desempenho no computador.<\/p>\n<h2>Sum\u00e1rio geral<\/h2>\n<p>Este guia foi dividido em cinco partes, de modo a ajudar tanto usu\u00e1rios iniciantes quanto usu\u00e1rios mais avan\u00e7ados de computador. Al\u00e9m disso, tentei reunir o m\u00e1ximo do meu conhecimento em tecnologia para ajudar da melhor forma poss\u00edvel.<\/p>\n<ol>\n<li><a title=\"O que s\u00e3o fontes ou letras japonesas do computador\" href=\"https:\/\/comoaprenderjapones.net\/vi\/o-que-sao-as-fontes-ou-letras-japonesas-do-computador\/\">O que s\u00e3o as letras japonesas do computador<\/a><\/li>\n<li><a title=\"Como instalar e remover letras japonesas do computador.\" href=\"https:\/\/comoaprenderjapones.net\/vi\/como-instalar-e-remover-letras-japonesas-do-computador\/\">Como instalar e remover as letras japonesas no computador<\/a><\/li>\n<li><a title=\"Os perigos de instalar muitas letras japonesas\" href=\"https:\/\/comoaprenderjapones.net\/vi\/os-perigos-de-instalar-muitas-letras-japonesas-no-computador\/\">Os perigos de instalar muitas letras japonesas<\/a><\/li>\n<li><a title=\"Como usar letras japonesas sem instalar\" href=\"https:\/\/comoaprenderjapones.net\/vi\/como-usar-letras-japonesas-sem-instalar\/\">Como usar uma letra japonesa sem instalar<\/a><\/li>\n<li><a title=\"Os gerenciadores de fontes e letras japonesas\" href=\"https:\/\/comoaprenderjapones.net\/vi\/os-gerenciadores-de-fontes-e-letras-japonesas\/\">Os gerenciadores de fontes<\/a><\/li>\n<\/ol>\n<p>Em todas as p\u00e1ginas relacionadas acima, voc\u00ea vai encontrar um guia de navega\u00e7\u00e3o indicando a p\u00e1gina atual e as pr\u00f3ximas p\u00e1ginas do guia sobre letras japonesas. Basta olhar o guia de navega\u00e7\u00e3o no final das p\u00e1ginas e continuar a leitura.<\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>N\u00e3o sei quantos de voc\u00eas s\u00e3o usu\u00e1rios iniciantes no ramo de tecnologia e computadores, mas como tenho recebido alguns e-mails perguntando como ver as letras japonesas no computador e como instalar estes tipos de arquivos.<\/p>","protected":false},"author":18,"featured_media":1438,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56,55],"tags":[53,57],"class_list":["post-1451","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fontes-japonesas","category-letras-japonesas","tag-escrever-em-japones","tag-letras-japonesas","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/comoaprenderjapones.net\/vi\/wp-json\/wp\/v2\/posts\/1451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comoaprenderjapones.net\/vi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comoaprenderjapones.net\/vi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comoaprenderjapones.net\/vi\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/comoaprenderjapones.net\/vi\/wp-json\/wp\/v2\/comments?post=1451"}],"version-history":[{"count":0,"href":"https:\/\/comoaprenderjapones.net\/vi\/wp-json\/wp\/v2\/posts\/1451\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comoaprenderjapones.net\/vi\/wp-json\/wp\/v2\/media\/1438"}],"wp:attachment":[{"href":"https:\/\/comoaprenderjapones.net\/vi\/wp-json\/wp\/v2\/media?parent=1451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comoaprenderjapones.net\/vi\/wp-json\/wp\/v2\/categories?post=1451"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comoaprenderjapones.net\/vi\/wp-json\/wp\/v2\/tags?post=1451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}