{"id":1598,"date":"2009-11-04T06:45:21","date_gmt":"2009-11-04T08:45:21","guid":{"rendered":"https:\/\/comoaprenderjapones.net\/?p=1598"},"modified":"2018-03-06T01:47:25","modified_gmt":"2018-03-06T04:47:25","slug":"rikaichan-dicionario-de-japones-gratis-para-firefox","status":"publish","type":"post","link":"https:\/\/comoaprenderjapones.net\/vi\/rikaichan-dicionario-de-japones-gratis-para-firefox\/","title":{"rendered":"Rikaichan &#8211; Dicion\u00e1rio de japon\u00eas gr\u00e1tis para Firefox"},"content":{"rendered":"<div class=\"3f06cfaed421c312d090106fe7464974\" data-index=\"2\" style=\"float: none; margin:0px;\">\n<script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-0652292147574552\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<!-- Ads responsivo Inicio Post CAJap -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-0652292147574552\"\r\n     data-ad-slot=\"3298668993\"\r\n     data-ad-format=\"auto\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p><em>Comece a usar agora a extens\u00e3o <strong>Rikaichan &#8211; Dicion\u00e1rio de japon\u00eas gr\u00e1tis para Firefox<\/strong>!<\/em><br \/>\n<img decoding=\"async\" class=\"wp-image-1599 size-full alignleft\" title=\"Rikaichan - Dicion\u00e1rio de japon\u00eas gr\u00e1tis para Firefox\" src=\"https:\/\/comoaprenderjapones.net\/wp-content\/uploads\/2018\/03\/rikaichan-dicionario-de-japones-gratis.jpg\" alt=\"Rikaichan - Dicion\u00e1rio de japon\u00eas gr\u00e1tis para Firefox\" width=\"150\" height=\"150\" srcset=\"https:\/\/comoaprenderjapones.net\/wp-content\/uploads\/2018\/03\/rikaichan-dicionario-de-japones-gratis.jpg 150w, https:\/\/comoaprenderjapones.net\/wp-content\/uploads\/2018\/03\/rikaichan-dicionario-de-japones-gratis-65x65.jpg 65w, https:\/\/comoaprenderjapones.net\/wp-content\/uploads\/2018\/03\/rikaichan-dicionario-de-japones-gratis-125x125.jpg 125w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/p>\n<p>Rikaichan \u00e9 um <a href=\"https:\/\/comoaprenderjapones.net\/vi\/dicionarios-de-japones-gratis\/\">dicion\u00e1rio de japon\u00eas<\/a> muito divulgado na Internet. Para mim, ele \u00e9 um forte concorrente ao t\u00e3o conhecido dicion\u00e1rio de japon\u00eas do Babylon. Suas principais vantagens s\u00e3o: ser um \u00f3timo dicion\u00e1rio de japon\u00eas, ser um plugin para navegador Mozilla FireFox e ainda por cima gr\u00e1tis.<\/p>\n<h2>Rikaichan &#8211; Dicion\u00e1rio de japon\u00eas gr\u00e1tis para Firefox<\/h2>\n<p>O que diferencia o Rikaichan dos outros dicion\u00e1rios de japon\u00eas \u00e9 o fato de traduzir kanjis apenas colocando o mouse sobre os s\u00edmbolos japoneses desconhecidos. Eu mesmo j\u00e1 baixei, experimentei e gostei muito de suas funcionalidades.<\/p>\n<p>O fato de ser um plugin para o navegador Mozilla FireFox torna a instala\u00e7\u00e3o muito f\u00e1cil e r\u00e1pida. Basta realizar uma busca na janela de complementos ou fazer uma pesquisa r\u00e1pida no site de extens\u00f5es do Mozilla.\u00a0<span id=\"more-249\"><\/span>Para facilitar as coisas, estou deixando os links para o plugin e o site do fabricante logo abaixo:<\/p>\n<p><strong>Site do fabricante<\/strong><br \/>\n<a href=\"http:\/\/www.polarcloud.com\/getrcx\/\" target=\"_blank\" rel=\"noopener\">http:\/\/www.polarcloud.com\/getrcx\/<\/a><\/p>\n<p><strong>Site da instala\u00e7\u00e3o do plugin no Mozila<\/strong><\/p>\n<p><a href=\"https:\/\/addons.mozilla.org\/en-US\/firefox\/addon\/rikaichamp\/\" target=\"_blank\" rel=\"noopener\">https:\/\/addons.mozilla.org\/en-US\/firefox\/addon\/rikaichamp\/<\/a><\/p>\n<p>Os dois pontos fracos do Rikaichan s\u00e3o o uso exclusivo no FireFox e a instala\u00e7\u00e3o separada dos dicion\u00e1rios de japon\u00eas. Depois de instalar o Rikaichan, \u00e9 preciso instalar um dos dicion\u00e1rios de japon\u00eas exibidos nas p\u00e1ginas acima. No meu caso, instalei o dicion\u00e1rio de japon\u00eas &#8211; ingl\u00eas. Infelizmente ainda n\u00e3o existe um dicion\u00e1rio de japon\u00eas &#8211; portugu\u00eas, mas o ingl\u00eas j\u00e1 facilita muito a tradu\u00e7\u00e3o de textos.<\/p>\n<h2>Dicas de como usar<\/h2>\n<p>O Rikaichan \u00e9 um dicion\u00e1rio de japon\u00eas gr\u00e1tis, personaliz\u00e1vel e muito f\u00e1cil de usar. Basta ativar o Rikaichan no FireFox para ele come\u00e7ar a funcionar. Ent\u00e3o, ao passar o mouse por cima de um kanji desconhecido, uma janela popup ser\u00e1 aberta com as informa\u00e7\u00f5es do <a href=\"https:\/\/comoaprenderjapones.net\/vi\/dicionarios-de-japones-gratis\/\">dicion\u00e1rio de japon\u00eas<\/a> sobre o kanji selecionado.<\/p>\n<p>Para ativar o Rikaichan:<\/p>\n<p>1. Aperte as teclas Alt + Insert(ins ou inserir)<br \/>\n2. Clique no menu Tools(Ferramentas) e selecionar a op\u00e7\u00e3o Rikaichan<br \/>\n3. Clique com o bot\u00e3o direito do mouse na p\u00e1gina e selecione a op\u00e7\u00e3o Rikaichan<\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Comece a usar agora a extens\u00e3o Rikaichan &#8211; Dicion\u00e1rio de japon\u00eas gr\u00e1tis para Firefox! Rikaichan \u00e9 um dicion\u00e1rio de japon\u00eas muito divulgado na Internet. Para mim, ele \u00e9 um forte concorrente ao t\u00e3o conhecido dicion\u00e1rio<\/p>","protected":false},"author":18,"featured_media":1602,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[51,67],"tags":[68,2,3],"class_list":["post-1598","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dicas-de-japones","category-dicionarios-de-japones-gratis","tag-dicionario-de-japones","tag-idioma-japones","tag-nihongo","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/comoaprenderjapones.net\/vi\/wp-json\/wp\/v2\/posts\/1598","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comoaprenderjapones.net\/vi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comoaprenderjapones.net\/vi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comoaprenderjapones.net\/vi\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/comoaprenderjapones.net\/vi\/wp-json\/wp\/v2\/comments?post=1598"}],"version-history":[{"count":0,"href":"https:\/\/comoaprenderjapones.net\/vi\/wp-json\/wp\/v2\/posts\/1598\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comoaprenderjapones.net\/vi\/wp-json\/wp\/v2\/media\/1602"}],"wp:attachment":[{"href":"https:\/\/comoaprenderjapones.net\/vi\/wp-json\/wp\/v2\/media?parent=1598"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comoaprenderjapones.net\/vi\/wp-json\/wp\/v2\/categories?post=1598"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comoaprenderjapones.net\/vi\/wp-json\/wp\/v2\/tags?post=1598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}