{"id":2140,"date":"2009-11-04T06:36:29","date_gmt":"2009-11-04T08:36:29","guid":{"rendered":"https:\/\/comoaprenderjapones.net\/?p=2140"},"modified":"2018-03-18T21:33:03","modified_gmt":"2018-03-19T00:33:03","slug":"como-permitir-e-proibir-em-japones","status":"publish","type":"post","link":"https:\/\/comoaprenderjapones.net\/vi\/como-permitir-e-proibir-em-japones\/","title":{"rendered":"Como permitir e proibir em japon\u00eas"},"content":{"rendered":"<div class=\"3f06cfaed421c312d090106fe7464974\" data-index=\"2\" style=\"float: none; margin:0px;\">\n<script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-0652292147574552\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<!-- Ads responsivo Inicio Post CAJap -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-0652292147574552\"\r\n     data-ad-slot=\"3298668993\"\r\n     data-ad-format=\"auto\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p><em>Logo abaixo aprenda a <strong>como permitir e proibir em japon\u00eas<\/strong>!<\/em><\/p>\n<p>De um modo geral, tanto as frases em japon\u00eas para pedir permiss\u00e3o quanto \u00e0s frases em japon\u00eas para proibir alguma a\u00e7\u00e3o, usam uma mistura dos\u00a0<a title=\"forma-te-dos-verbos-em-japones\" href=\"https:\/\/comoaprenderjapones.net\/vi\/forma-te-dos-verbos-em-japones\/\">verbos japoneses na forma te<\/a>\u00a0e algumas express\u00f5es bem comuns na\u00a0l\u00edngua japonesa.<\/p>\n<h2>Como permitir e proibir em japon\u00eas<\/h2>\n<p>No artigo de hoje, vamos conversar um pouco sobre as formas mais b\u00e1sicas de construir frases usadas para dar permiss\u00e3o e proibir algu\u00e9m de fazer algo em japon\u00eas.<\/p>\n<h2>Como permitir e pedir permiss\u00e3o em japon\u00eas<\/h2>\n<p>Para dar ou pedir permiss\u00e3o em japon\u00eas, \u00e9 necess\u00e1rio seguir uma estrutura b\u00e1sica de frases, usando os\u00a0<a title=\"forma-te-dos-verbos-em-japones\" href=\"https:\/\/comoaprenderjapones.net\/vi\/forma-te-dos-verbos-em-japones\/\">verbos japoneses na forma te<\/a>, a part\u00edcula\u00a0<acronym title=\"mo\">\u3082<\/acronym>\u00a0e uma das express\u00f5es abaixo:<\/p>\n<p><acronym title=\"yoroshii desu. - Tudo bem; tudo certo; posso?; \u00e9 permitido?...\">\u5b9c\u3057\u3044\u3067\u3059\u3002<\/acronym><br \/>\n<acronym title=\"ii desu - Tudo bem; tudo certo; posso?; \u00e9 permitido?...\">\u3044\u3044\u3067\u3059\u3002<\/acronym><br \/>\n<acronym title=\"kamaimasen - N\u00e3o possui um significado espec\u00edfico, mas neste caso pode ser traduzido como 'poder'.\">\u304b\u307e\u3044\u307e\u305b\u3093\u3002<\/acronym><\/p>\n<p>As formas apresentadas acima s\u00e3o mais usadas em conversas formais. No caso de informalidade \u00e9 poss\u00edvel usar\u00a0<acronym title=\"kamaiwanai\">\u304b\u307e\u308f\u306a\u3044<\/acronym>,\u00a0<acronym title=\"moii\">\u3082\u3044\u3044<\/acronym>\u00a0ou\u00a0<acronym title=\"ii\">\u3044\u3044<\/acronym>\u00a0sem a necessidade de usar\u00a0<acronym title=\"desu\">\u3067\u3059<\/acronym>no final das frases. Os exemplos abaixo ilustram melhor os casos de formalidade e informalidade para pedir permiss\u00e3o em japon\u00eas.<\/p>\n<p><strong>Formal<\/strong><\/p>\n<p><acronym title=\"yoroshii desu. - Tudo bem; tudo certo; posso?; \u00e9 permitido?...\">\u5b9c\u3057\u3044\u3067\u3059\u3002<\/acronym>\u00a0\u00a0&#8211;\u00a0<acronym title=\"terebi o mite mo yoroshii desu ka? - Posso (\u00e9 poss\u00edvel) ver televis\u00e3o?\">\u30c6\u30ec\u30d3\u3092\u898b\u3066\u3082\u5b9c\u3057\u3044\u3067\u3059\u304b\uff1f<\/acronym><br \/>\n<acronym title=\"ii desu - Tudo bem; tudo certo; posso?; \u00e9 permitido?...\">\u3044\u3044\u3067\u3059\u3002<\/acronym>\u00a0\u00a0&#8211;\u00a0<acronym title=\"terebi o mite mo ii desu ka? - Posso (\u00e9 permitido) ver televis\u00e3o?\">\u30c6\u30ec\u30d3\u3092\u898b\u3066\u3082\u3044\u3044\u3067\u3059\u304b\uff1f<\/acronym><br \/>\n<acronym title=\"kamaimasen\">\u304b\u307e\u3044\u307e\u305b\u3093<\/acronym>\u3002-\u00a0<acronym title=\"terebi o mite mo kamaimasen ka? - Posso (\u00e9 permitido) ver televis\u00e3o?\">\u30c6\u30ec\u30d3\u3092\u898b\u3066\u3082\u304b\u307e\u3044\u307e\u305b\u3093\u304b\uff1f<\/acronym><\/p>\n<p><strong>Informal<\/strong><br \/>\n<acronym title=\"kawanai - Vers\u00e3o informal de kamaimasen.\">\u304b\u307e\u308f\u306a\u3044<\/acronym>\u00a0&#8211;\u00a0<acronym title=\"terebi o mite mo kawanai - Posso (\u00e9 permitido) ver televis\u00e3o.\">\u30c6\u30ec\u30d3\u3092\u898b\u3066\u3082\u304b\u308f\u306a\u3044<\/acronym><br \/>\n<acronym title=\"ii - Tudo bem; tudo certo; posso?; \u00e9 permitido?...\">\u3044\u3044<\/acronym>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0&#8211;\u00a0<acronym title=\"terebi o mite mo ii - Posso (\u00e9 permitido) ver televis\u00e3o.\">\u30c6\u30ec\u30d3\u3092\u898b\u3066\u3082\u3044\u3044<\/acronym><\/p>\n<p><strong>Coloquial<\/strong><br \/>\n<acronym title=\"ii - Tudo bem; tudo certo; posso?; \u00e9 permitido?...\">\u3044\u3044<\/acronym>\u00a0&#8211;\u00a0<acronym title=\"terebi o mite ii - Posso (\u00e9 permitido) ver televis\u00e3o.\">\u30c6\u30ec\u30d3\u3092\u898b\u3066\u3044\u3044<\/acronym><\/p>\n<p>Note que, para transformar a frase numa pergunta, basta adicionar a part\u00edcula\u00a0<acronym title=\"ka\">\u304b<\/acronym>\u00a0ao final da frase em japon\u00eas, usando o mesmo caminho que estudamos no artigo &#8220;<a title=\"Como fazer perguntas em japon\u00eas\" href=\"https:\/\/comoaprenderjapones.net\/vi\/como-fazer-perguntas-em-japones\/\">como fazer perguntas em japon\u00eas<\/a>&#8220;.<\/p>\n<p>Abaixo, seguem mais alguns exemplos sobre como dar e pedir permiss\u00e3o em japon\u00eas.<\/p>\n<p><acronym title=\"koko ni suwatte mo ii desu ka? - Posso (\u00e9 permitido) sentar aqui?\">\u3053\u3053\u306b\u5ea7\u3063\u3066\u3082\u3044\u3044\u3067\u3059\u304b\uff1f<\/acronym><br \/>\n<acronym title=\"kono sushi o tabete mo yoroshii desu ka? - Posso (\u00e9 permitido) comer este sushi?\">\u3053\u306e\u5bff\u53f8\u3092\u98df\u3079\u3066\u3082\u5b9c\u3057\u3044\u3067\u3059\u304b\uff1f<\/acronym><br \/>\n<acronym title=\"nihongo no jisho o tsukatte mo ii - Pode usar o dicion\u00e1rio de japon\u00eas.\">\u65e5\u672c\u8a9e\u306e\u8f9e\u66f8\u3092\u4f7f\u3063\u3066\u3082\u3044\u3044\u3002<\/acronym><br \/>\n<\/p>\n<h2>Como proibir em japon\u00eas<\/h2>\n<p>Proibir alguma a\u00e7\u00e3o em japon\u00eas \u00e9 algo t\u00e3o simples quanto dar permiss\u00e3o, onde usamos um caminho semelhante para construir as frases. S\u00f3 que neste caso, \u00e9 mais comum usar a part\u00edcula\u00a0<acronym title=\"wa\">\u306f<\/acronym>.<\/p>\n<p>Sendo assim, para proibir algo em japon\u00eas, vamos precisar dos\u00a0verbos na forma te, adicionando a <a href=\"https:\/\/comoaprenderjapones.net\/vi\/particulas-basicas-parte-1-%e3%81%af-e-%e3%81%8c\/\">part\u00edcula\u00a0<acronym title=\"wa\">\u306f<\/acronym><\/a>\u00a0e uma das express\u00f5es relacionadas abaixo.<\/p>\n<p><strong>Formal<\/strong><br \/>\n<acronym title=\"narimasen\">\u306a\u308a\u307e\u305b\u3093<\/acronym>\u00a0&#8211;\u00a0<acronym title=\"terebi o mite wa narimasen. - N\u00e3o pode (n\u00e3o \u00e9 permitido) ver televis\u00e3o.\">\u30c6\u30ec\u30d3\u3092\u898b\u3066\u306f\u306a\u308a\u307e\u305b\u3093\u3002<\/acronym><br \/>\n<acronym title=\"ikemasen\">\u3044\u3051\u307e\u305b\u3093<\/acronym>\u00a0&#8211;\u00a0<acronym title=\"terebi o mite wa ikemasen - N\u00e3o pode (n\u00e3o \u00e9 permitido) ver televis\u00e3o.\">\u30c6\u30ec\u30d3\u3092\u898b\u3066\u306f\u3044\u3051\u307e\u305b\u3093\u3002<\/acronym><\/p>\n<p><strong>Informal<\/strong><br \/>\n<acronym title=\"naranai - vers\u00e3o informal de narimasen\">\u306a\u3089\u306a\u3044<\/acronym>\u00a0&#8211;\u00a0<acronym title=\"terebi o mite wa naranai - N\u00e3o pode (n\u00e3o \u00e9 permitido) ver televis\u00e3o.\">\u30c6\u30ec\u30d3\u3092\u898b\u3066\u306f\u306a\u3089\u306a\u3044\u3002<\/acronym><br \/>\n<acronym title=\"ikenai - vers\u00e3o informal de ikemasen.\">\u3044\u3051\u306a\u3044<\/acronym>\u00a0&#8211;\u00a0<acronym title=\"terebi o mite wa ikenai - N\u00e3o pode (n\u00e3o \u00e9 permitido) ver televis\u00e3o.\">\u30c6\u30ec\u30d3\u3092\u898b\u3066\u306f\u3044\u3051\u306a\u3044\u3002<\/acronym><br \/>\n<acronym title=\"dameda - proibido, imposs\u00edvel...\">\u3060\u3081\u3060<\/acronym>\u00a0&#8211;\u00a0<acronym title=\"terebi o mite wa dameda - N\u00e3o pode (n\u00e3o \u00e9 permitido) ver televis\u00e3o.\">\u30c6\u30ec\u30d3\u3092\u898b\u3066\u306f\u3060\u3081\u3060\u3002<\/acronym><\/p>\n<p><strong>Coloquial<\/strong><br \/>\n<acronym title=\"chadame - vers\u00e3o muito informal de dameda.\">\u3061\u3083\u3060\u3081<\/acronym>\u00a0&#8211;\u00a0<acronym title=\"terebi o mite chadame. - N\u00e3o pode (n\u00e3o \u00e9 permitido) ver televis\u00e3o.\">\u30c6\u30ec\u30d3\u3092\u898b\u3061\u3083\u3060\u3081\u3002<\/acronym><\/p>\n<p>Abaixo seguem alguns exemplos sobre como proibir em japon\u00eas:<\/p>\n<p><acronym title=\"nihongo no hon wo tsukatte wa dameda - N\u00e3o pode (n\u00e3o \u00e9 poss\u00edvel, \u00e9 proibido) usar o livro de japon\u00eas.\">\u65e5\u672c\u8a9e\u306e\u672c\u3092\u4f7f\u3063\u3066\u306f\u3060\u3081\u3060\u3002<\/acronym><br \/>\n<acronym title=\"sushi o tabete wa narimasen - N\u00e3o pode (n\u00e3o \u00e9 poss\u00edvel, \u00e9 proibido) comer sushi.\">\u5bff\u53f8\u3092\u98df\u3079\u3066\u306f\u306a\u308a\u307e\u305b\u3093\u3002<\/acronym><\/p>\n<p>Hoje, achei melhor falar sobre esse assunto de um modo meio superficial, mas nos pr\u00f3ximos artigos, voltaremos a conversar sobre esse tema de modo mais profundo.<\/p>\n<h2>Exerc\u00edcio de caligrafia de kanjis<\/h2>\n<p>Abaixo seguem os\u00a0<a href=\"https:\/\/comoaprenderjapones.net\/vi\/como-escrever-as-letras-japonesas-kanjis\/\">s\u00edmbolos japoneses ideogr\u00e1ficos<\/a>\u00a0usados neste artigo. Selecionando os kanjis desejados copie-os e cole na\u00a0<a href=\"https:\/\/comoaprenderjapones.net\/vi\/in\/imprimir-para-treinar-kanas-e-kanjis\/\" target=\"_blank\" rel=\"noopener\">Planilha para pr\u00e1tica de Kana e Kanji<\/a>\u00a0, ser\u00e1 aberta uma nova janela onde voc\u00ea vai poder ver\u00a0o arquivo para impress\u00e3o e praticar a caligrafia japonesa cobrindo os s\u00edmbolos cinzas e depois tentando escrever sozinho. \u00c9 s\u00f3 imprimir e praticar.<\/p>\n<table style=\"height: 106px\" border=\"0\" width=\"410\" cellspacing=\"2\" cellpadding=\"2\">\n<tbody>\n<tr>\n<td align=\"left\" valign=\"middle\">\u5b9c<\/td>\n<td align=\"left\" valign=\"middle\">\u898b<\/td>\n<td align=\"left\" valign=\"middle\">\u5ea7<\/td>\n<td align=\"left\" valign=\"middle\">\u5bff<\/td>\n<td align=\"left\" valign=\"middle\">\u53f8<\/td>\n<\/tr>\n<tr>\n<td align=\"left\" valign=\"middle\">\u98df<\/td>\n<td align=\"left\" valign=\"middle\">\u65e5<\/td>\n<td align=\"left\" valign=\"middle\">\u672c<\/td>\n<td align=\"left\" valign=\"middle\">\u8a9e<\/td>\n<td align=\"left\" valign=\"middle\">\u8f9e<\/td>\n<\/tr>\n<tr>\n<td align=\"left\" valign=\"middle\">\u66f8<\/td>\n<td align=\"left\" valign=\"middle\">\u4f7f<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Logo abaixo aprenda a como permitir e proibir em japon\u00eas! De um modo geral, tanto as frases em japon\u00eas para pedir permiss\u00e3o quanto \u00e0s frases em japon\u00eas para proibir alguma a\u00e7\u00e3o, usam uma mistura dos\u00a0verbos<\/p>","protected":false},"author":18,"featured_media":2143,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[49,70,73],"tags":[69,2,3],"class_list":["post-2140","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curso-de-japones-gratis","category-gramatica-japonesa","category-verbos-em-japones","tag-curso-japones-gratis","tag-idioma-japones","tag-nihongo","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/comoaprenderjapones.net\/vi\/wp-json\/wp\/v2\/posts\/2140","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comoaprenderjapones.net\/vi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comoaprenderjapones.net\/vi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comoaprenderjapones.net\/vi\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/comoaprenderjapones.net\/vi\/wp-json\/wp\/v2\/comments?post=2140"}],"version-history":[{"count":0,"href":"https:\/\/comoaprenderjapones.net\/vi\/wp-json\/wp\/v2\/posts\/2140\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comoaprenderjapones.net\/vi\/wp-json\/wp\/v2\/media\/2143"}],"wp:attachment":[{"href":"https:\/\/comoaprenderjapones.net\/vi\/wp-json\/wp\/v2\/media?parent=2140"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comoaprenderjapones.net\/vi\/wp-json\/wp\/v2\/categories?post=2140"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comoaprenderjapones.net\/vi\/wp-json\/wp\/v2\/tags?post=2140"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}