{"id":1713,"date":"2009-11-03T05:14:28","date_gmt":"2009-11-03T07:14:28","guid":{"rendered":"https:\/\/comoaprenderjapones.net\/?p=1713"},"modified":"2018-03-11T15:19:02","modified_gmt":"2018-03-11T18:19:02","slug":"adjetivos-na-em-japones","status":"publish","type":"post","link":"https:\/\/comoaprenderjapones.net\/zh_cn\/adjetivos-na-em-japones\/","title":{"rendered":"Os adjetivos na em japon\u00eas"},"content":{"rendered":"<div class=\"7e456065ddfc52bba92c3508f25583df\" data-index=\"2\" style=\"float: none; margin:0px;\">\n<script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-0652292147574552\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<!-- Ads responsivo Inicio Post CAJap -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-0652292147574552\"\r\n     data-ad-slot=\"3298668993\"\r\n     data-ad-format=\"auto\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p><em>Aprenda agora mais sobre <strong>os adjetivos na em japon\u00eas<\/strong>!<\/em><\/p>\n<p>Nos artigos anteriores sobre <a href=\"https:\/\/comoaprenderjapones.net\/zh_cn\/adjetivos-japoneses\/\">\u65e5\u8bed\u5f62\u5bb9\u8bcd<\/a>, entendemos os tipos de adjetivos e as flex\u00f5es dos adjetivos japoneses\u00a0<acronym title=\"i\">\u3044<\/acronym>. No artigo de hoje vamos conhecer as flex\u00f5es dos adjetivos japoneses\u00a0<acronym title=\"\u5728\">\u306a<\/acronym>.<\/p>\n<h2>Os adjetivos na em japon\u00eas<\/h2>\n<p>No que diz respeito \u00e0 flex\u00e3o desses adjetivos em japon\u00eas, a gram\u00e1tica japonesa foi muito boa conosco. Os adjetivos\u00a0<acronym title=\"\u5728\">\u306a<\/acronym>\u00a0n\u00e3o mudam de forma de acordo com os tempos verbais. Para indicar a ideia de tempo, normalmente usamos\u00a0<a title=\"Desu - \u65e5\u8bed\u4e2d\u7684 &quot;\u662f &quot;\u52a8\u8bcd\" href=\"https:\/\/comoaprenderjapones.net\/zh_cn\/desu-o-verbo-ser-em-japones\/\">os tempos verbais de desu<\/a>.<\/p>\n<p>Como os tempos verbais s\u00e3o indicados por\u00a0<acronym title=\"desu\">\u3067\u3059<\/acronym>, ele pode aparecer nos modos formais ou informais. Seguindo as regras da gram\u00e1tica japonesa, \u00e9 bem prov\u00e1vel que voc\u00ea encontre\u00a0<acronym title=\"da - ser\">\u3060<\/acronym>,\u00a0<acronym title=\"\u5185\">\u306a\u3044<\/acronym>\u00a0ou at\u00e9\u00a0<acronym title=\"nakatta\">\u306a\u304b\u3063\u305f<\/acronym>\u00a0no final das frases em lugar das formas comuns de\u00a0<acronym title=\"desu\">\u3067\u3059<\/acronym>.<\/p>\n<h2>O presente afirmativo dos adjetivos na em japon\u00eas<\/h2>\n<p>Segundo a gram\u00e1tica japonesa, a forma mais b\u00e1sica dos adjetivos\u00a0<acronym title=\"\u5728\">\u306a<\/acronym>\u00a0\u00e9 simplesmente o nome do adjetivo seguido pela s\u00edlaba\u00a0<acronym title=\"\u5728\">\u306a<\/acronym>. Apesar disso, dentro das frases, \u00e9 bem comum omitir a s\u00edlaba\u00a0<acronym title=\"\u5728\">\u306a<\/acronym>\u00a0quando o adjetivo em japon\u00eas aparece seguido de\u00a0<acronym title=\"desu\">\u3067\u3059<\/acronym>.<\/p>\n<p><acronym title=\"taisetsu na hon desu - Livros importantes.\"><span class=\"orange\" style=\"color: #ff0000\">\u5927\u5207<\/span><span class=\"blue\" style=\"color: #00ccff\">\u306a\u672c\u3067\u3059<\/span>\u3002<\/acronym><\/p>\n<p><acronym title=\"kono hon wa taisetsu desu - Este livro \u00e9 importante.\">\u3053\u306e\u672c\u306f<span class=\"orange\" style=\"color: #ff0000\">\u5927\u5207<\/span><span class=\"blue\" style=\"color: #00ccff\">\u3067\u3059<\/span>\u3002<\/acronym><br \/>\n<\/p>\n<h2>O passado afirmativo dos adjetivos na em japon\u00eas<\/h2>\n<p>Para colocar um adjetivo japon\u00eas\u00a0<acronym title=\"\u5728\">\u306a<\/acronym>\u00a0no passado, basta flexionar o verbo\u00a0<acronym title=\"desu\">\u3067\u3059<\/acronym>\u00a0para o passado afirmativo.<\/p>\n<p><acronym title=\"Kono hon wa taisetsu deshita \u2013 Este livro era importante.\">\u3053\u306e\u672c\u306f<span class=\"orange\" style=\"color: #ff0000\">\u5927\u5207<\/span><span class=\"blue\" style=\"color: #00ccff\">\u3067\u3057\u305f<\/span>\u3002<\/acronym><\/p>\n<p><acronym title=\"Yamada-san wa shizuka deshita \u2013 O senhor Yamada era calmo.\">\u5c71\u7530\u3055\u3093\u306f<span class=\"orange\">\u3057<span style=\"color: #ff0000\">\u305a\u304b<\/span><\/span><span class=\"blue\" style=\"color: #00ccff\">\u3067\u3057\u305f<\/span>\u3002<\/acronym><\/p>\n<h2>O presente negativo dos adjetivos na em japon\u00eas<\/h2>\n<p>O presente negativo dos adjetivos japoneses na \u00e9 feto com o <a href=\"https:\/\/comoaprenderjapones.net\/zh_cn\/desu-o-verbo-ser-em-japones\/\">verbo\u00a0<acronym title=\"desu\">\u3067\u3059<\/acronym><\/a>\u00a0tamb\u00e9m no presente negativo. Dessa forma, teremos:<\/p>\n<p><acronym title=\"Kono hon wa taisetsu dewa arimasen. - Este livro n\u00e3o \u00e9 importante.\">\u3053\u306e\u672c\u306f<span class=\"orange\" style=\"color: #ff0000\">\u5927\u5207<\/span><span class=\"blue\"><span style=\"color: #00ccff\">\u3067\u306f\u3042\u308a\u307e\u305b\u3093<\/span>\u3002<\/span><\/acronym><\/p>\n<p><acronym title=\"Yamada-san wa shizuka dewa arimasen. - O senhor Yamada n\u00e3o \u00e9 calmo.\">\u5c71\u7530\u3055\u3093\u306f<span class=\"orange\">\u3057<span style=\"color: #ff0000\">\u305a\u304b<\/span><\/span><span class=\"blue\"><span style=\"color: #00ccff\">\u3067\u306f\u3042\u308a\u307e\u305b\u3093<\/span>\u3002<\/span><\/acronym><\/p>\n<h2>O passado negativo dos adjetivos japoneses na em japon\u00eas<\/h2>\n<p>Do mesmo modo que os outros tempos dos adjetivos japoneses\u00a0<acronym title=\"\u5728\">\u306a<\/acronym>, o passado negativo \u00e9 feito com o verbo\u00a0<acronym title=\"desu\">\u3067\u3059<\/acronym>\u00a0no mesmo tempo verbal: o passado negativo.<\/p>\n<p><acronym title=\"Kono hon wa taisetsu dewa arimasen deshita. - Este livro n\u00e3o era importante.\">\u3053\u306e\u672c\u306f<span class=\"orange\" style=\"color: #ff0000\">\u5927\u5207<\/span><span class=\"blue\"><span style=\"color: #00ccff\">\u3067\u306f\u3042\u308a\u307e\u305b\u3093\u3067\u3057\u305f<\/span>\u3002<\/span><\/acronym><\/p>\n<p><acronym title=\"Yamada-san wa shizuka dewa arimasen deshita. - O senhor Yamada n\u00e3o era calmo.\">\u5c71\u7530\u3055\u3093\u306f<span class=\"orange\">\u3057<span style=\"color: #ff0000\">\u305a\u304b<\/span><\/span><span class=\"blue\"><span style=\"color: #00ccff\">\u3067\u306f\u3042\u308a\u307e\u305b\u3093\u3067\u3057\u305f<\/span>\u3002<\/span><\/acronym><\/p>\n<h2>\u6c49\u5b57\u4e66\u6cd5\u7ec3\u4e60<\/h2>\n<p>\u4ee5\u4e0b\u662f\u00a0<a href=\"https:\/\/comoaprenderjapones.net\/zh_cn\/%e5%a6%82%e4%bd%95%e4%b9%a6%e5%86%99%e6%97%a5%e8%af%ad%e6%b1%89%e5%ad%97\/\">\u65e5\u672c\u8868\u610f\u7b26\u53f7<\/a>\u00a0\u5728\u672c\u6587\u4e2d\u4f7f\u7528\u3002\u9009\u62e9\u60a8\u60f3\u8981\u7684\u6c49\u5b57\uff0c\u7136\u540e\u5c06\u5176\u590d\u5236\u5e76\u7c98\u8d34\u5230\u00a0<a href=\"https:\/\/comoaprenderjapones.net\/zh_cn\/in\/imprimir-para-treinar-kanas-e-kanjis\/\" target=\"_blank\" rel=\"noopener\">\u5047\u540d\u548c\u6c49\u5b57\u7ec3\u4e60\u4f5c\u4e1a\u7eb8<\/a>\u00a0\u5728\u6253\u5f00\u7684\u65b0\u7a97\u53e3\u4e2d\uff0c\u60a8\u53ef\u4ee5\u67e5\u770b\u53ef\u6253\u5370\u6587\u4ef6\uff0c\u5e76\u901a\u8fc7\u8986\u76d6\u7070\u8272\u7b26\u53f7\u6765\u7ec3\u4e60\u65e5\u8bed\u4e66\u6cd5\uff0c\u7136\u540e\u5c1d\u8bd5\u81ea\u5df1\u4e66\u5199\u3002\u53ea\u9700\u6253\u5370\u51fa\u6765\u5e76\u7ec3\u4e60\u5373\u53ef\u3002<\/p>\n<table style=\"height: 43px\" border=\"0\" width=\"329\" cellspacing=\"2\" cellpadding=\"2\">\n<tbody>\n<tr>\n<td align=\"left\" valign=\"middle\">\u5927<\/td>\n<td align=\"left\" valign=\"middle\">\u5207<\/td>\n<td align=\"left\" valign=\"middle\">\u672c<\/td>\n<td align=\"left\" valign=\"middle\">\u5c71<\/td>\n<td align=\"left\" valign=\"middle\">\u7530<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Aprenda agora mais sobre os adjetivos na em japon\u00eas! Nos artigos anteriores sobre adjetivos em japon\u00eas, entendemos os tipos de adjetivos e as flex\u00f5es dos adjetivos japoneses\u00a0\u3044. No artigo de hoje vamos conhecer as flex\u00f5es<\/p>","protected":false},"author":18,"featured_media":1714,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[76,49,70],"tags":[69,27,71,2,3],"class_list":["post-1713","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-adjetivos-japoneses","category-curso-de-japones-gratis","category-gramatica-japonesa","tag-curso-japones-gratis","tag-gramatica","tag-gramatica-japonesa","tag-idioma-japones","tag-nihongo"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/comoaprenderjapones.net\/wp-content\/uploads\/2018\/03\/adjetivos-na-em-japones.png?fit=500%2C400&ssl=1","jetpack-related-posts":[{"id":1719,"url":"https:\/\/comoaprenderjapones.net\/zh_cn\/como-usar-adjetivos-em-japones\/","url_meta":{"origin":1713,"position":0},"title":"Como usar adjetivos em japon\u00eas","author":"L\u00edngua Japonesa","date":"3 de 11 \u6708 de 2009","format":false,"excerpt":"Aprenda agora a como usar adjetivos em japon\u00eas! Segundo a gram\u00e1tica japonesa, os adjetivos em japon\u00eas podem ser usados de v\u00e1rias formas diferentes, contudo as formas de uso mais comuns s\u00e3o antes e depois dos substantivos. Como usar adjetivos em japon\u00eas Passe o cursor do mouse sobre os s\u00edmbolos japoneses\u2026","rel":"","context":"\u5728\u201cAdjetivos japoneses\u201d\u4e2d","block_context":{"text":"Adjetivos japoneses","link":"https:\/\/comoaprenderjapones.net\/zh_cn\/adjetivos-japoneses\/"},"img":{"alt_text":"Como usar adjetivos em japon\u00eas - \u305d\u308c\u306f\u9752\u3044\u672c\u3067\u3059\u304b\uff1f","src":"https:\/\/i0.wp.com\/comoaprenderjapones.net\/wp-content\/uploads\/2018\/03\/como-usar-os-adjetivos-em-japones.png?fit=500%2C400&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1706,"url":"https:\/\/comoaprenderjapones.net\/zh_cn\/adjetivos-i-em-japones\/","url_meta":{"origin":1713,"position":1},"title":"Os adjetivos i em japon\u00eas","author":"L\u00edngua Japonesa","date":"3 de 11 \u6708 de 2009","format":false,"excerpt":"Vamos agora conhecer\u00a0os adjetivos i em japon\u00eas! Como j\u00e1 conhecemos superficialmente os adjetivos em japon\u00eas, chegou o momento de aprofundarmos um pouco mais no assunto dos adjetivos japoneses. \u00c9 neste ponto que a gram\u00e1tica japonesa demora a ser compreendida por iniciantes em\u00a0l\u00edngua japonesa. Todos n\u00f3s conhecemos o conceito de flex\u00e3o\u2026","rel":"","context":"\u5728\u201cAdjetivos japoneses\u201d\u4e2d","block_context":{"text":"Adjetivos japoneses","link":"https:\/\/comoaprenderjapones.net\/zh_cn\/adjetivos-japoneses\/"},"img":{"alt_text":"Os adjetivos i em japon\u00eas - \u65b0\u3057\u3044\u30dc\u30fc\u30eb","src":"https:\/\/i0.wp.com\/comoaprenderjapones.net\/wp-content\/uploads\/2009\/11\/adjetivos-i-em-japones.png?fit=500%2C400&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1699,"url":"https:\/\/comoaprenderjapones.net\/zh_cn\/tipos-de-adjetivos-em-japones\/","url_meta":{"origin":1713,"position":2},"title":"Os tipos de adjetivos em japon\u00eas","author":"L\u00edngua Japonesa","date":"3 de 11 \u6708 de 2009","format":false,"excerpt":"Conhe\u00e7a os tipos de adjetivos em japon\u00eas e aprenda mais! Antes de come\u00e7ar a falar sobre os adjetivos japoneses propriamente ditos, vamos ver uma descri\u00e7\u00e3o geral sobre os tipos de adjetivos encontrados na l\u00edngua japonesa. Passe o cursor do mouse sobre os s\u00edmbolos japoneses (kanjis) para ver a pron\u00fancia e\u2026","rel":"","context":"\u5728\u201cCurso de Japon\u00eas Gr\u00e1tis\u201d\u4e2d","block_context":{"text":"Curso de Japon\u00eas Gr\u00e1tis","link":"https:\/\/comoaprenderjapones.net\/zh_cn\/curso-de-japones-gratis\/"},"img":{"alt_text":"Os tipos de adjetivos em japon\u00eas - \u9752\u3044\u8eca","src":"https:\/\/i0.wp.com\/comoaprenderjapones.net\/wp-content\/uploads\/2009\/11\/tipos-de-adjetivos-em-japones.png?fit=500%2C400&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2103,"url":"https:\/\/comoaprenderjapones.net\/zh_cn\/verbos-em-japones-na-forma-tai\/","url_meta":{"origin":1713,"position":3},"title":"TAI \u5f62\u5f0f\u7684\u65e5\u8bed\u52a8\u8bcd","author":"L\u00edngua Japonesa","date":"4 de 11 \u6708 de 2009","format":false,"excerpt":"Os verbos em japon\u00eas na forma TAI-\u00a0\u00a0\u305f\u3044\u00a0s\u00e3o usados para expressar o desejo de realizar uma atividade espec\u00edfica. Por causa disso, essa forma dos verbos em japon\u00eas se utiliza muito dos verbos de a\u00e7\u00e3o. Verbos em japon\u00eas na forma TAI O presente e os verbos na forma tai Para utilizar a\u2026","rel":"","context":"\u5728\u201cCurso de Japon\u00eas Gr\u00e1tis\u201d\u4e2d","block_context":{"text":"Curso de Japon\u00eas Gr\u00e1tis","link":"https:\/\/comoaprenderjapones.net\/zh_cn\/curso-de-japones-gratis\/"},"img":{"alt_text":"Verbos em japon\u00eas na forma TAI - \u8cb7\u3044\u305f\u3044","src":"https:\/\/i0.wp.com\/comoaprenderjapones.net\/wp-content\/uploads\/2009\/11\/verbos-em-japones-na-forma-tai.png?fit=500%2C400&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1771,"url":"https:\/\/comoaprenderjapones.net\/zh_cn\/os-adverbios-em-japones\/","url_meta":{"origin":1713,"position":4},"title":"\u65e5\u8bed\u526f\u8bcd","author":"L\u00edngua Japonesa","date":"3 de 11 \u6708 de 2009","format":false,"excerpt":"Conhe\u00e7a mais sobre\u00a0os adv\u00e9rbios em japon\u00eas com exemplos! Muitos j\u00e1 devem saber que adv\u00e9rbios s\u00e3o palavras invari\u00e1veis que modificam ou adicionam significado aos verbos e adjetivos. Os adv\u00e9rbios japoneses podem indicar tempo, freq\u00fc\u00eancia e v\u00e1rias outras situa\u00e7\u00f5es dependendo da frase. Passe o cursor do mouse sobre os s\u00edmbolos japoneses para\u2026","rel":"","context":"\u5728\u201cCurso de Japon\u00eas Gr\u00e1tis\u201d\u4e2d","block_context":{"text":"Curso de Japon\u00eas Gr\u00e1tis","link":"https:\/\/comoaprenderjapones.net\/zh_cn\/curso-de-japones-gratis\/"},"img":{"alt_text":"Os adv\u00e9rbios em japon\u00eas","src":"https:\/\/i0.wp.com\/comoaprenderjapones.net\/wp-content\/uploads\/2009\/11\/os-adverbios-em-japones.png?fit=500%2C400&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1604,"url":"https:\/\/comoaprenderjapones.net\/zh_cn\/curso-de-japones-gratis-guia-de-estudos\/","url_meta":{"origin":1713,"position":5},"title":"Curso de japon\u00eas gr\u00e1tis &#8211; Guia de estudos","author":"L\u00edngua Japonesa","date":"16 de 11 \u6708 de 2009","format":false,"excerpt":"Veja aqui a lista completa dos posts publicados para o\u00a0Curso de japon\u00eas gr\u00e1tis - Guia de estudos! Est\u00e1 p\u00e1gina funciona como um guia de estudos para o curso de japon\u00eas gr\u00e1tis do L\u00edngua Japonesa, onde qualquer interessado poder\u00e1 aprender japon\u00eas online gratuitamente. O objetivo \u00e9 reunir o m\u00e1ximo de conhecimento\u2026","rel":"","context":"\u5728\u201cCurso de Japon\u00eas Gr\u00e1tis\u201d\u4e2d","block_context":{"text":"Curso de Japon\u00eas Gr\u00e1tis","link":"https:\/\/comoaprenderjapones.net\/zh_cn\/curso-de-japones-gratis\/"},"img":{"alt_text":"Como formar frases em japon\u00eas","src":"https:\/\/i0.wp.com\/comoaprenderjapones.net\/wp-content\/uploads\/2014\/09\/nihongo_idioma.jpg?fit=477%2C296&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/comoaprenderjapones.net\/zh_cn\/wp-json\/wp\/v2\/posts\/1713","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comoaprenderjapones.net\/zh_cn\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comoaprenderjapones.net\/zh_cn\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comoaprenderjapones.net\/zh_cn\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/comoaprenderjapones.net\/zh_cn\/wp-json\/wp\/v2\/comments?post=1713"}],"version-history":[{"count":0,"href":"https:\/\/comoaprenderjapones.net\/zh_cn\/wp-json\/wp\/v2\/posts\/1713\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comoaprenderjapones.net\/zh_cn\/wp-json\/wp\/v2\/media\/1714"}],"wp:attachment":[{"href":"https:\/\/comoaprenderjapones.net\/zh_cn\/wp-json\/wp\/v2\/media?parent=1713"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comoaprenderjapones.net\/zh_cn\/wp-json\/wp\/v2\/categories?post=1713"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comoaprenderjapones.net\/zh_cn\/wp-json\/wp\/v2\/tags?post=1713"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}